{"id":19425,"date":"2022-12-02T17:26:30","date_gmt":"2022-12-02T22:26:30","guid":{"rendered":"https:\/\/www.gambyl.com\/?p=19425"},"modified":"2022-12-02T17:26:35","modified_gmt":"2022-12-02T22:26:35","slug":"resumo-da-fase-de-grupos-da-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/","title":{"rendered":"Copa do Mundo Catar 2022 \u2013 Resumo da fase de grupos"},"content":{"rendered":"<p><a href=\"https:\/\/www.gambyl.com\/pt\/copa-do-mundo\/\">A Copa do Mundo de 2022 no Catar<\/a> ser\u00e1 lembrado por muitas coisas, e uma delas ser\u00e1 o grande n\u00famero de surpresas que teve na fase de grupos, onde tivemos vit\u00f3rias e elimina\u00e7\u00f5es inesperadas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013\u00a0<strong>Grupo A<\/strong><\/h2>\n\n\n\n<p>O Grupo A pode ser aquele onde n\u00e3o houve surpresas. A Holanda chegou como a Sele\u00e7\u00e3o Nacional mais forte e foi, embora n\u00e3o tanto quanto o esperado.&nbsp;<strong>Venceu o Senegal (2-0) e o Catar (2-0) e empatou com o Equador (1-1)<\/strong>, mas os torcedores sabem que precisam continuar melhorando se quiserem ser campe\u00f5es. Nas oitavas de final, eles enfrentar\u00e3o os Estados Unidos.<\/p>\n\n\n\n<p>O outro qualificado foi o Senegal,&nbsp;<strong>que no \u00faltimo jogo venceu o Equador (2-1) e arrebatou o segundo lugar. Apesar de n\u00e3o ter Sadio Man\u00e9<\/strong>, os africanos mostraram que possuem mais atributos e confiaram muito na sua ordem e for\u00e7a f\u00edsica. Agora eles v\u00e3o jogar contra a Inglaterra.<\/p>\n\n\n\n<p>O Equador, por sua vez, ficou triste ap\u00f3s a elimina\u00e7\u00e3o apesar de ter feito um grande jogo contra a Holanda, enquanto a sele\u00e7\u00e3o local, o Catar, n\u00e3o somou nenhum ponto e marcou apenas 1 gol em sua estreia na Copa do Mundo, e deixou uma imagem ruim ap\u00f3s tendo sido campe\u00e3o da Copa Asi\u00e1tica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo B<\/strong><\/h2>\n\n\n\n<p><strong>No Grupo B tamb\u00e9m n\u00e3o tivemos muitas emo\u00e7\u00f5es depois de a Inglaterra ter passado sem problemas como primeira ap\u00f3s as goleadas frente ao Ir\u00e3o (6-2) e ao Pa\u00eds de Gales (3-0)<\/strong>. Com os Estados Unidos n\u00e3o passou de um empate sem gols e nesse jogo a sele\u00e7\u00e3o teve algumas lacunas. Harry Kane ainda n\u00e3o conseguiu marcar e s\u00e3o os jovens que t\u00eam defendido a equipa no ataque. Eles ter\u00e3o que lutar muito contra o Senegal e os africanos s\u00e3o muito f\u00edsicos.<\/p>\n\n\n\n<p><strong>Os Estados Unidos conquistaram a vaga gra\u00e7as a um gol do Capit\u00e3o Am\u00e9rica, Christian Pulisic, no jogo contra o Ir\u00e3 (1-0)<\/strong>. A sele\u00e7\u00e3o norte-americana tem a melhor gera\u00e7\u00e3o da sua hist\u00f3ria e n\u00e3o quer perder a oportunidade. Por\u00e9m, tem tido problemas para marcar gols: s\u00f3 conseguiu marcar dois. Devemos destacar ainda a defesa da equipa j\u00e1 que sofreu apenas 1 golo e foi de grande penalidade. Enfrentar\u00e1 a Holanda nas oitavas de final e n\u00e3o sabe se poder\u00e1 contar com Pulisic, que ainda est\u00e1 lesionado.<\/p>\n\n\n\n<p>Entre os eliminados, o Ir\u00e3 deixou boas sensa\u00e7\u00f5es e lutou at\u00e9 o fim para chegar \u00e0s oitavas de final, mas perdeu para os Estados Unidos.&nbsp;<strong>O Pa\u00eds de Gales, por sua vez, foi uma das grandes decep\u00e7\u00f5es, conseguindo apenas 1 ponto e 1 gol de Gareth Bale de p\u00eanalti<\/strong>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo C<\/strong><\/h2>\n\n\n\n<p><strong>O Grupo C foi aquele que come\u00e7ou com surpresas j\u00e1 que no primeiro jogo a Ar\u00e1bia Saudita voltou a vencer a Argentina por 2 a 1. Depois a &#039;Albiceleste&#039; se recuperou nos jogos seguintes, vencendo M\u00e9xico e Pol\u00f4nia, ambos por 2 a 0<\/strong>, classificando-se assim como primeiro do grupo e melhorando a cada dia. Jovens jogadores como Enzo Fern\u00e1ndez, Alexis Mac Allister e Juli\u00e1n \u00c1lvarez t\u00eam sido as estrelas da equipe. Lionel Messi fez uma boa Copa do Mundo e marcou 2 gols, embora tamb\u00e9m tenha perdido um p\u00eanalti. Eles agora enfrentar\u00e3o a Austr\u00e1lia nas oitavas de final e devem avan\u00e7ar com tranquilidade.<\/p>\n\n\n\n<p><strong>A segunda classificada foi a Pol\u00f3nia, que sofreu muito no \u00faltimo jogo para manter a vaga. Estava perdendo por 2 a 0 com a Argentina e o M\u00e9xico vencendo a Ar\u00e1bia Saudita por 2 a 0<\/strong>, e essas duas equipes estavam iguais em todos os itens de desempate, ent\u00e3o tiveram que ir para os cart\u00f5es amarelos e os poloneses tiveram menos que os mexicanos. A sele\u00e7\u00e3o europeia se dedicou mais que tudo para n\u00e3o cometer faltas para se classificar. Por\u00e9m, a Ar\u00e1bia Saudita marcou um gol e garantiu a passagem. A Pol\u00f4nia avan\u00e7a como um dos rivais mais fracos nas oitavas de final, mas tem como grande artilheiro Robert Lewandowski e o melhor goleiro at\u00e9 agora em Wojciech Szczesny, que defendeu 2 p\u00eanaltis. Seu rival ser\u00e1 a Fran\u00e7a.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p>O M\u00e9xico deixar\u00e1 o Catar por apenas uma diferen\u00e7a insignificante. Por\u00e9m, n\u00e3o fez uma boa Copa do Mundo, mostrando um p\u00e9ssimo jogo contra Pol\u00f4nia e Argentina, e s\u00f3 lembrou de atacar na \u00faltima partida contra a Ar\u00e1bia Saudita.&nbsp;<strong>Marcaram 2 gols, ambos contra os \u00e1rabes, e sofreram 3. O melhor jogador do time no torneio foi o goleiro Guillermo Ochoa<\/strong>.<\/p>\n\n\n\n<p><strong>Apesar de ter ficado em \u00faltimo lugar, a Ar\u00e1bia Saudita surpreendeu a todos na Copa do Mundo, principalmente com a vit\u00f3ria sobre a Argentina (2 a 1)<\/strong>. Eles foram uma pedra no sapato com seu estilo de jogo, adiantando-se muito nas defesas e jogando no contra-ataque.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo D<\/strong><\/h2>\n\n\n\n<p><strong>A Fran\u00e7a foi uma das primeiras sele\u00e7\u00f5es a se classificar gra\u00e7as \u00e0s vit\u00f3rias sobre a Austr\u00e1lia (4-1) e a Dinamarca (2-1), e por isso decidiu colocar suplentes contra a Tun\u00edsia (0-1), jogo que perdido.<\/strong>&nbsp;A equipa de Didier Deschamps tem jogado muito bem e jogadores como Kylian Mbapp\u00e9 e Antoine Griezmann est\u00e3o em boa forma, assim como a dupla de meio-campo formada por Adrien Rabiot e Aur\u00e9lien Tchouam\u00e9ni. Levar em conta que sempre receberam um gol. A Pol\u00f3nia ser\u00e1 a sua rival nos oitavos-de-final e n\u00e3o acreditamos que ser\u00e1 dif\u00edcil para eles.<\/p>\n\n\n\n<p><strong>A Austr\u00e1lia foi uma das surpresas da Copa do Mundo ao eliminar a Dinamarca, vencendo por 1 a 0 no \u00faltimo jogo e ficando com o segundo lugar. Al\u00e9m disso, os australianos venceram a Tun\u00edsia por 1 a 0 e perderam para a Fran\u00e7a por 4 a 1<\/strong>, por isso podem dizer que s\u00e3o eficazes na marca\u00e7\u00e3o de golos em cada um dos jogos, mas honestamente o que t\u00eam mostrado \u00e9 muito fraco e n\u00e3o acreditamos que sejam um advers\u00e1rio da Argentina.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p><strong>A Tun\u00edsia despediu-se decentemente ao vencer a Fran\u00e7a por 1-0 e empatar com a Dinamarca (0-0)<\/strong>, jogando um futebol muito bom, e at\u00e9 o \u00faltimo momento sonhava com a classifica\u00e7\u00e3o, mas isso n\u00e3o dependia de si.<\/p>\n\n\n\n<p>Se a Tun\u00edsia se despediu de cabe\u00e7a erguida, a Dinamarca f\u00ea-lo de cabe\u00e7a baixa.&nbsp;<strong>Empataram com a Tun\u00edsia (0-0) e perderam para Fran\u00e7a (2-1) e Austr\u00e1lia (1-0).<\/strong>&nbsp;Virou um time que tocava e tocava na bola, mas faltava ideias ofensivas e faltava peso para frente para fazer gols. Foi uma das grandes decep\u00e7\u00f5es do Catar 2022 desde que chegou como semifinalista da Eurocopa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo E<\/strong><\/h2>\n\n\n\n<p>O grupo de surpresas. Incrivelmente,&nbsp;<strong>O Jap\u00e3o venceu Espanha e Alemanha, ambas por 2 a 1, e depois de come\u00e7ar a perder, ficou em primeiro lugar, eliminando os alem\u00e3es. A sele\u00e7\u00e3o japonesa mostrou ordem e efic\u00e1cia, embora tenha deixado d\u00favidas ap\u00f3s a derrota frente \u00e0 Costa Rica (1-0).<\/strong>&nbsp;Pode-se dizer que fizeram o mais dif\u00edcil e falharam no mais f\u00e1cil. No entanto, ser\u00e1 um advers\u00e1rio dif\u00edcil para a Cro\u00e1cia e \u00e9 poss\u00edvel, a priori, o jogo mais equilibrado nas oitavas de final.<\/p>\n\n\n\n<p><strong>A Espanha fez um grande primeiro jogo onde derrotou a Costa Rica (7-0), mas foi apenas uma miragem. Depois a equipe de Luis Enrique mostrou a mesma coisa nos \u00faltimos anos: muita posse de bola, mas nenhum gol.<\/strong>&nbsp;Foi de mais para menos e perdeu no \u00faltimo jogo e deixou uma m\u00e1 impress\u00e3o antes das oitavas de final, onde ter\u00e1 que lutar contra um Marrocos surpreendente.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p>A Alemanha est\u00e1 novamente fora da fase de grupos de uma Copa do Mundo depois da desastrosa R\u00fassia 2018 e isso \u00e9 preocupante.&nbsp;<strong>Perdeu para o Jap\u00e3o (2 a 1), empatou com a Espanha (1 a 1) e venceu a Costa Rica no final (4 a 2), al\u00e9m de deixar uma imagem muito ruim.&nbsp;<\/strong>Entre os pontos positivos est\u00e1 o jovem Jamal Musiala (19 anos), que fez jogos muito bons e \u00e9 uma das estrelas do futuro. Da mesma forma, alguns jogadores como Thomas M\u00fcller encerraram a carreira na Sele\u00e7\u00e3o Nacional.<\/p>\n\n\n\n<p><strong>A Costa Rica come\u00e7ou mal, perdendo por 7 a 0 para a Espanha, mas depois melhorou. Venceu o Jap\u00e3o por 1-0, embora s\u00f3 tenha feito um remate \u00e0 baliza, e contra a Alemanha, embora tenha perdido (4-2)<\/strong>, deixaram uma imagem muito boa no segundo tempo e \u00e9 essa imagem que os costarriquenhos esperam que os torcedores lembrem.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo F<\/strong><\/h2>\n\n\n\n<p><strong>Marrocos foi outra das grandes surpresas, ao realizar uma fase de grupos muito boa, onde venceu a B\u00e9lgica (2-0) e o Canad\u00e1 (2-1), e empatou com a Cro\u00e1cia (0-0).<\/strong>\u00a0Os africanos jogaram um futebol muito bom, com grandes jogadores e comandados por Hakim Ziyech, deixando os belgas, atual n\u00famero 2 do mundo, na estrada. O mais importante desta equipa \u00e9 que est\u00e1 muito motivada e ter\u00e1 pela frente um rival especial, com quem tem muitas diferen\u00e7as pol\u00edticas e hist\u00f3ricas. Assim, ter\u00e1 muito mais vontade de entrar em campo e poder\u00e1 ter mais uma grande surpresa.<\/p>\n\n\n\n<p><strong>A Cro\u00e1cia alternou bons jogos com maus jogos, mas acabou por se classificar em parte devido ao mau ataque da B\u00e9lgica, que os perdoou no \u00faltimo jogo (0-0). Os croatas, atuais vice-campe\u00f5es mundiais, s\u00f3 conseguiram vencer o Canad\u00e1 (4-1),<\/strong>&nbsp;e eles t\u00eam muitas defici\u00eancias, ent\u00e3o ser\u00e1 dif\u00edcil para eles contra o Jap\u00e3o, que \u00e9 mais organizado.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p>A B\u00e9lgica foi outra das grandes decep\u00e7\u00f5es da Copa do Mundo, ficando eliminada na primeira fase. Os belgas ficaram em segundo lugar no mundo, mas isso n\u00e3o foi demonstrado em campo.&nbsp;<strong>Venceu o Canad\u00e1 (1-0) no primeiro jogo mas jogou mal, depois perdeu para Marrocos (2-0) e quando mais precisou jogou bem (frente \u00e0 Cro\u00e1cia), mas j\u00e1 era tarde.<\/strong>&nbsp;Durante o torneio tiveram muitos problemas dentro da equipe e com certeza ser\u00e1 o fim de sua gera\u00e7\u00e3o de ouro.<\/p>\n\n\n\n<p>O Canad\u00e1 mostrou coisas boas, mas n\u00e3o foi suficiente e despediu-se sem pontos, embora Alphonso Davies tenha marcado o primeiro gol da hist\u00f3ria de seu pa\u00eds em uma Copa do Mundo. Os norte-americanos somaram uma experi\u00eancia importante para a pr\u00f3xima Copa do Mundo, que ser\u00e1 em casa.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo G<\/strong><\/h2>\n\n\n\n<p><strong>O Brasil n\u00e3o foi a equipe avassaladora que se esperava, mas venceu seus dois primeiros jogos contra a S\u00e9rvia (2-0) e a Su\u00ed\u00e7a (1-0) e se classificou para as oitavas de final.<\/strong>&nbsp;Contra Camar\u00f5es jogou com reservas e perdeu por 1 a 0, sofrendo um gol depois de muito tempo. A equipa de Tit\u00e9 continua a ser a mais forte candidata ao t\u00edtulo, mas j\u00e1 percebeu que as coisas n\u00e3o v\u00e3o ser f\u00e1ceis e que ter\u00e1 que trabalhar muito mais. Nas oitavas de final, enfrentar\u00e1 uma Coreia do Sul ordeira e ter\u00e1 de volta Neymar, lesionado ap\u00f3s o primeiro jogo.<\/p>\n\n\n\n<p><strong>A Su\u00ed\u00e7a fez um grande jogo na \u00faltima partida da fase de grupos e venceu a S\u00e9rvia por 3 a 2 para se classificar para as oitavas de final. Os su\u00ed\u00e7os tamb\u00e9m venceram Camar\u00f5es (1 a 0) e fizeram um grande jogo contra o Brasil (0 a 1)<\/strong>, mostrando que \u00e9 um forte rival a ser respeitado. Breel Embolo marcou 2 gols e \u00e9 o artilheiro do time. Portugal ser\u00e1 o seu rival.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p><strong>Camar\u00f5es se despediu fazendo algo que poucos podem dizer que fizeram: vencer o Brasil. Um golo de Vincent Aboubakar aos 90+2 minutos foi suficiente para os africanos triunfarem, mas n\u00e3o foi suficiente. Dias antes haviam feito um grande jogo contra a S\u00e9rvia, empatando em 3 a 3, onde o pr\u00f3prio Aboubakar era figura.<\/strong>&nbsp;Os africanos despedem-se do Qatar com um sorriso no rosto.<\/p>\n\n\n\n<p>Ao contr\u00e1rio, a S\u00e9rvia, que apesar de ter uma grande equipa e alguns grandes avan\u00e7ados, ficou em \u00faltimo lugar no seu grupo com apenas 1 ponto.&nbsp;<strong>Os Balc\u00e3s tiveram uma defesa ruim, sofrendo muitos gols, e isso cobrou seu pre\u00e7o. Na \u00faltima jornada fizeram-nos um grande jogo contra a Su\u00ed\u00e7a mas n\u00e3o foi suficiente e perderam por 2-3, despedindo-se desta Copa do Mundo.<\/strong><\/p>\n\n\n\n<div id=\"advad-gambyl-2102304491\" class=\"house advad-gambyl-third-paragraph advad-gambyl-entity-placement\" style=\"margin-top: 10px;margin-right: 10px;margin-bottom: 10px;margin-left: 10px;clear: both;\" data-cfpa=\"31717\" data-cfpw=\"31717\"><h2><strong><span style=\"color:#F0BE00;font-weight:800;\">Aten\u00e7\u00e3o novos jogadores!<\/span><\/strong><\/h2>\r\n\t<img src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA4MDAgMTk3IiB3aWR0aD0iODAwIiBoZWlnaHQ9IjE5NyIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDI0JTJGMDclMkZHYW1ieWxfZ29sZF9sb2dvcy13aGl0ZS1zcGFuaXNoLTEucG5nIiBkYXRhLXc9IjgwMCIgZGF0YS1oPSIxOTciIGRhdGEtYmlwPSIiPjwvc3ZnPg==\" data-spai=\"1\" alt=\"Gambyl\" width=\"125\" height=\"36\">\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Aposte em esportes legalmente na Bolsa de Apostas Gambyl. Oferta para novos jogadores: $10 USD para todas as novas contas verificadas, mais um b\u00f4nus de 100% no seu primeiro dep\u00f3sito.<\/a><\/p>\t\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Junte-se hoje!<\/a><\/p>\r\n<\/div><br style=\"clear: both; display: block; float: none;\"\/><script type=\"text\/javascript\">;new advadsCfpAd( 31717 );<\/script><h2 class=\"wp-block-heading\">Resumo da fase de grupos da Copa do Mundo \u2013 <strong>Grupo H<\/strong><\/h2>\n\n\n\n<p><strong>Um grupo que foi definido de forma agonizante. Portugal qualificou-se primeiro gra\u00e7as \u00e0s vit\u00f3rias sobre o Gana (3-2) e o Uruguai (2-0) e chegou ao \u00faltimo jogo contra a Coreia do Sul (1-2) com uma equipa de suplentes para serem os ju\u00edzes.&nbsp;<\/strong>No que diz respeito ao seu n\u00edvel, Bruno Fernandes foi o l\u00edder desta equipa e eles jogam ao ritmo que ele estabelece. N\u00e3o \u00e9 a equipa mais forte, mas est\u00e1 muito unida e isso \u00e9 muito importante. Na pr\u00f3xima rodada, enfrentar\u00e1 a Su\u00ed\u00e7a em uma partida muito dif\u00edcil.<\/p>\n\n\n\n<p><strong>A Coreia do Sul alcan\u00e7ou a qualifica\u00e7\u00e3o de forma angustiante com um golo de Hee-Chan Hwang aos 90+1 minutos, ap\u00f3s um grande passe de Heung-Min Son que serviu para vencer Portugal por 2-1.<\/strong>&nbsp;Os coreanos ficaram na quadra assistindo ao outro jogo que estava sendo disputado naquele momento no celular para comemorar, e assim fizeram. Assim como a maioria das sele\u00e7\u00f5es asi\u00e1ticas, os coreanos foram muito ordeiros e confiaram nos contra-ataques para marcar. Nas oitavas de final ter\u00e1 o rival que ningu\u00e9m quer: o Brasil.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">\u2013<\/h3>\n\n\n\n<p>A \u00faltima imagem do Uruguai \u00e9 ver Luis Su\u00e1rez chorando.&nbsp;<strong>A sele\u00e7\u00e3o sul-americana venceu Gana por 2 a 0 no \u00faltimo jogo, mas n\u00e3o foi suficiente e ficou em terceiro lugar do grupo em n\u00famero de gols marcados (a Coreia fez 4 e eles 2), mas a verdade \u00e9 que teve uma p\u00e9ssima torneio e somente no \u00faltimo jogo saiu para jogar em busca da vit\u00f3ria e se contentou com o 2x0.<\/strong>&nbsp;O t\u00e9cnico trouxe os melhores jogadores e depois veio o gol sul-coreano que obrigou a marcar mais um, mas j\u00e1 era tarde e eles voltaram para casa na primeira rodada.<\/p>\n\n\n\n<p><strong>Gana lutou e lutou, mas n\u00e3o foi suficiente. A sele\u00e7\u00e3o africana perdeu com Portugal (2-3) e Uruguai (0-2) e venceu a Coreia do Sul (3-2).<\/strong>&nbsp;Os seus jogos foram muito emocionantes e o Mohammed Kudus fez uma grande ta\u00e7a, mas n\u00e3o foi suficiente. Eles foram um grande animador, mas, como h\u00e1 12 anos, o Uruguai voltou a ser o seu carrasco, vencendo-os na \u00faltima partida e eliminando-os.<\/p>","protected":false},"excerpt":{"rendered":"<p>The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup &#8211;\u00a0Group A Group A may be one where there were no surprises. The Netherlands [&hellip;]<\/p>","protected":false},"author":1,"featured_media":19428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[98,90,1141],"tags":[171],"class_list":["post-19425","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betting","category-football","category-world-cup","tag-soccer"],"aioseo_notices":[],"modified_by":"Erwin Noguera","aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.6.2 - aioseo.com -->\n\t<meta name=\"description\" content=\"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gambyl Nation Editorial Team\"\/>\n\t<meta name=\"google-site-verification\" content=\"g4nMgEUwH_EUeAHO1on7tJ8dc_UVEdTvD7NXvjDBtYI\" \/>\n\t<meta name=\"msvalidate.01\" content=\"11AACE468E54A2AFF018B9903D7E59EC\" \/>\n\t<meta name=\"p:domain_verify\" content=\"2dd0267387e90e116bf3240265818d71\" \/>\n\t<meta name=\"yandex-verification\" content=\"07d0c340775b3ea0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.6.2\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gambyl Sports Betting Exchange - Bet on Sports Where The House Never Wins\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange\" \/>\n\t\t<meta property=\"og:description\" content=\"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.gambyl.com\/wp-content\/uploads\/2022\/12\/World-Cup-Qatar-2022-\u2013-Group-Stage-Roundup.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.gambyl.com\/wp-content\/uploads\/2022\/12\/World-Cup-Qatar-2022-\u2013-Group-Stage-Roundup.jpg\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1388\" \/>\n\t\t<meta property=\"og:image:height\" content=\"924\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-12-02T22:26:30+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-12-02T22:26:35+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/realgambyl\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@realgambyl\" \/>\n\t\t<meta name=\"twitter:title\" content=\"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange\" \/>\n\t\t<meta name=\"twitter:description\" content=\"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@realgambyl\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/new.gambyl.com\/wp-content\/uploads\/2021\/01\/gambyl_logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#blogposting\",\"name\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup - Gambyl Sports Betting Exchange\",\"headline\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup\",\"author\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/World-Cup-Qatar-2022-\\u2013-Group-Stage-Roundup.jpg\",\"width\":1388,\"height\":924,\"caption\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup\"},\"datePublished\":\"2022-12-02T17:26:30-06:00\",\"dateModified\":\"2022-12-02T17:26:35-06:00\",\"inLanguage\":\"pt-PT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#webpage\"},\"articleSection\":\"Betting, Football, World Cup, soccer\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/#listItem\",\"name\":\"Football\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/#listItem\",\"position\":2,\"name\":\"Football\",\"item\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#listItem\",\"name\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#listItem\",\"position\":3,\"name\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/#listItem\",\"name\":\"Football\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\",\"name\":\"Gambyl Sports Betting Exchange\",\"description\":\"Bet on Sports Where The House Never Wins\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"email\":\"hola@gambyl.com\",\"telephone\":\"+19012059469\",\"foundingDate\":\"2022-06-01\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-gambyl_logo.jpg\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#organizationLogo\",\"width\":512,\"height\":512,\"caption\":\"Gambyl Thumbnail Logo Purple\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/realgambyl\\\/\",\"https:\\\/\\\/twitter.com\\\/realgambyl\\\/\",\"https:\\\/\\\/instagram.com\\\/realgambyl_es\\\/\",\"https:\\\/\\\/tiktok.com\\\/@realgambyl\",\"https:\\\/\\\/www.pinterest.ca\\\/realgambyl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7DMuQpsBQaIsDhTcGQt-Ow\",\"https:\\\/\\\/reddit.com\\\/r\\\/gambyl\",\"https:\\\/\\\/discord.gg\\\/dZewkvMNgx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/\",\"name\":\"Gambyl Nation Editorial Team\",\"description\":\"Gambyl sports betting staff writers based are based in Mexico, South America and Canada. Our editorial writing team have combined experience of over 50 years in the sports betting and handicapping industries as both players and industry pros.\",\"jobTitle\":\"Staff Writer\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-gambyl_logo.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#webpage\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/\",\"name\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup - Gambyl Sports Betting Exchange\",\"description\":\"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/World-Cup-Qatar-2022-\\u2013-Group-Stage-Roundup.jpg\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#mainImage\",\"width\":1388,\"height\":924,\"caption\":\"World Cup Qatar 2022 \\u2013 Group Stage Roundup\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/futebol-americano\\\/resumo-da-fase-de-grupos-da-copa-do-mundo\\\/#mainImage\"},\"datePublished\":\"2022-12-02T17:26:30-06:00\",\"dateModified\":\"2022-12-02T17:26:35-06:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"name\":\"Gambyl Sports Betting Exchange\",\"alternateName\":\"Gambyl Sports\",\"description\":\"Bet on Sports Where The House Never Wins\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\"}}]}<\/script>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"hxcfb9ve51\");\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange<\/title>\n\n","aioseo_head_json":{"title":"Copa do Mundo Qatar 2022 \u2013 Resumo da fase de grupos - Gambyl Sports Betting Exchange","description":"A Copa do Mundo de 2022 no Catar ser\u00e1 lembrada por muitas coisas, e uma delas ser\u00e1 o grande n\u00famero de surpresas que teve na fase de grupos, onde tivemos vit\u00f3rias e elimina\u00e7\u00f5es inesperadas. Resumo da Fase de Grupos da Copa do Mundo - Grupo A O Grupo A pode ser aquele onde n\u00e3o houve surpresas. Os Pa\u00edses Baixos","canonical_url":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"g4nMgEUwH_EUeAHO1on7tJ8dc_UVEdTvD7NXvjDBtYI","msvalidate.01":"11AACE468E54A2AFF018B9903D7E59EC","p:domain_verify":"2dd0267387e90e116bf3240265818d71","yandex-verification":"07d0c340775b3ea0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#blogposting","name":"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange","headline":"World Cup Qatar 2022 \u2013 Group Stage Roundup","author":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"publisher":{"@id":"https:\/\/www.gambyl.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMzg4IDkyNCIgd2lkdGg9IjEzODgiIGhlaWdodD0iOTI0IiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjIlMkYxMiUyRldvcmxkLUN1cC1RYXRhci0yMDIyLSVFMiU4MCU5My1Hcm91cC1TdGFnZS1Sb3VuZHVwLmpwZyIgZGF0YS13PSIxMzg4IiBkYXRhLWg9IjkyNCIgZGF0YS1iaXA9IiI+PC9zdmc+","width":1388,"height":924,"caption":"World Cup Qatar 2022 \u2013 Group Stage Roundup"},"datePublished":"2022-12-02T17:26:30-06:00","dateModified":"2022-12-02T17:26:35-06:00","inLanguage":"pt-PT","mainEntityOfPage":{"@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#webpage"},"isPartOf":{"@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#webpage"},"articleSection":"Betting, Football, World Cup, soccer"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/#listItem","position":1,"name":"Home","item":"https:\/\/www.gambyl.com\/pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/#listItem","name":"Football"}},{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/#listItem","position":2,"name":"Football","item":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#listItem","name":"World Cup Qatar 2022 \u2013 Group Stage Roundup"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#listItem","position":3,"name":"World Cup Qatar 2022 \u2013 Group Stage Roundup","previousItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/#listItem","name":"Football"}}]},{"@type":"Organization","@id":"https:\/\/www.gambyl.com\/pt\/#organization","name":"Gambyl Sports Betting Exchange","description":"Bet on Sports Where The House Never Wins","url":"https:\/\/www.gambyl.com\/pt\/","email":"hola@gambyl.com","telephone":"+19012059469","foundingDate":"2022-06-01","logo":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA1MTIgNTEyIiB3aWR0aD0iNTEyIiBoZWlnaHQ9IjUxMiIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDElMkZjcm9wcGVkLWdhbWJ5bF9sb2dvLmpwZyIgZGF0YS13PSI1MTIiIGRhdGEtaD0iNTEyIiBkYXRhLWJpcD0iIj48L3N2Zz4=","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#organizationLogo","width":512,"height":512,"caption":"Gambyl Thumbnail Logo Purple"},"image":{"@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/realgambyl\/","https:\/\/twitter.com\/realgambyl\/","https:\/\/instagram.com\/realgambyl_es\/","https:\/\/tiktok.com\/@realgambyl","https:\/\/www.pinterest.ca\/realgambyl\/","https:\/\/www.youtube.com\/channel\/UC7DMuQpsBQaIsDhTcGQt-Ow","https:\/\/reddit.com\/r\/gambyl","https:\/\/discord.gg\/dZewkvMNgx"]},{"@type":"Person","@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author","url":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/","name":"Gambyl Nation Editorial Team","description":"Gambyl sports betting staff writers based are based in Mexico, South America and Canada. Our editorial writing team have combined experience of over 50 years in the sports betting and handicapping industries as both players and industry pros.","jobTitle":"Staff Writer","image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA1MTIgNTEyIiB3aWR0aD0iNTEyIiBoZWlnaHQ9IjUxMiIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDElMkZjcm9wcGVkLWdhbWJ5bF9sb2dvLmpwZyIgZGF0YS13PSI1MTIiIGRhdGEtaD0iNTEyIiBkYXRhLWJpcD0iIj48L3N2Zz4="}},{"@type":"WebPage","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#webpage","url":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/","name":"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange","description":"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/www.gambyl.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#breadcrumblist"},"author":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"creator":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMzg4IDkyNCIgd2lkdGg9IjEzODgiIGhlaWdodD0iOTI0IiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjIlMkYxMiUyRldvcmxkLUN1cC1RYXRhci0yMDIyLSVFMiU4MCU5My1Hcm91cC1TdGFnZS1Sb3VuZHVwLmpwZyIgZGF0YS13PSIxMzg4IiBkYXRhLWg9IjkyNCIgZGF0YS1iaXA9IiI+PC9zdmc+","@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#mainImage","width":1388,"height":924,"caption":"World Cup Qatar 2022 \u2013 Group Stage Roundup"},"primaryImageOfPage":{"@id":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/#mainImage"},"datePublished":"2022-12-02T17:26:30-06:00","dateModified":"2022-12-02T17:26:35-06:00"},{"@type":"WebSite","@id":"https:\/\/www.gambyl.com\/pt\/#website","url":"https:\/\/www.gambyl.com\/pt\/","name":"Gambyl Sports Betting Exchange","alternateName":"Gambyl Sports","description":"Bet on Sports Where The House Never Wins","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/www.gambyl.com\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Gambyl Sports Betting Exchange - Bet on Sports Where The House Never Wins","og:type":"article","og:title":"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange","og:description":"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands","og:url":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/","og:image":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMzg4IDkyNCIgd2lkdGg9IjEzODgiIGhlaWdodD0iOTI0IiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjIlMkYxMiUyRldvcmxkLUN1cC1RYXRhci0yMDIyLSVFMiU4MCU5My1Hcm91cC1TdGFnZS1Sb3VuZHVwLmpwZyIgZGF0YS13PSIxMzg4IiBkYXRhLWg9IjkyNCIgZGF0YS1iaXA9IiI+PC9zdmc+","og:image:secure_url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMzg4IDkyNCIgd2lkdGg9IjEzODgiIGhlaWdodD0iOTI0IiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjIlMkYxMiUyRldvcmxkLUN1cC1RYXRhci0yMDIyLSVFMiU4MCU5My1Hcm91cC1TdGFnZS1Sb3VuZHVwLmpwZyIgZGF0YS13PSIxMzg4IiBkYXRhLWg9IjkyNCIgZGF0YS1iaXA9IiI+PC9zdmc+","og:image:width":1388,"og:image:height":924,"article:published_time":"2022-12-02T22:26:30+00:00","article:modified_time":"2022-12-02T22:26:35+00:00","article:publisher":"https:\/\/facebook.com\/realgambyl\/","twitter:card":"summary_large_image","twitter:site":"@realgambyl","twitter:title":"World Cup Qatar 2022 \u2013 Group Stage Roundup - Gambyl Sports Betting Exchange","twitter:description":"The 2022 World Cup in Qatar will be remembered for many things, and one of those will be the large number of surprises it had in the group stage, where we had unexpected victories and eliminations. World Cup Group Stage Roundup - Group A Group A may be one where there were no surprises. The Netherlands","twitter:creator":"@realgambyl","twitter:image":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxIDEiIHdpZHRoPSIxIiBoZWlnaHQ9IjEiIGRhdGEtdT0iaHR0cHMlM0ElMkYlMkZuZXcuZ2FtYnlsLmNvbSUyRndwLWNvbnRlbnQlMkZ1cGxvYWRzJTJGMjAyMSUyRjAxJTJGZ2FtYnlsX2xvZ28ucG5nIiBkYXRhLXc9IjEiIGRhdGEtaD0iMSIgZGF0YS1iaXA9IiI+PC9zdmc+"},"aioseo_meta_data":{"post_id":"19425","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":0,"reviewed_by":null,"open_ai":null,"ai":null,"created":"2023-10-26 07:13:02","updated":"2025-06-02 23:54:02"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.gambyl.com\/pt\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.gambyl.com\/pt\/futebol-americano\/\" title=\"Football\">Football<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\tWorld Cup Qatar 2022 \u2013 Group Stage Roundup\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.gambyl.com\/pt\/"},{"label":"Football","link":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/"},{"label":"World Cup Qatar 2022 \u2013 Group Stage Roundup","link":"https:\/\/www.gambyl.com\/pt\/futebol-americano\/resumo-da-fase-de-grupos-da-copa-do-mundo\/"}],"authors":[],"_links":{"self":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts\/19425","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/comments?post=19425"}],"version-history":[{"count":0,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts\/19425\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/media\/19428"}],"wp:attachment":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/media?parent=19425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/categories?post=19425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/tags?post=19425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}