{"id":40407,"date":"2025-01-09T15:49:36","date_gmt":"2025-01-09T21:49:36","guid":{"rendered":"https:\/\/www.gambyl.com\/?p=40407"},"modified":"2025-01-09T15:49:39","modified_gmt":"2025-01-09T21:49:39","slug":"noite-de-luta-ufc-dern-vs-ribas-2","status":"publish","type":"post","link":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/","title":{"rendered":"UFC Fight Night: Dern vs Ribas 2 Probabilidades e escolhas do card de luta"},"content":{"rendered":"<p>O UFC est\u00e1 levando a pr\u00f3xima noite de luta para o UFC Apex em Las Vegas, Nevada, e teremos uma revanche que foi remarcada de meados de dezembro para dar a este evento sua luta principal, com dois pesos-palha se enfrentando para ver quem tem mais chances de disputar o pr\u00f3ximo t\u00edtulo poss\u00edvel.<br><br>Nosso evento principal neste s\u00e1bado \u00e0 noite ser\u00e1 entre Mackenzie Dern e Amanda Ribas, que se enfrentaram em outubro de 2019 e querem se enfrentar novamente para ver quem consegue ganhar for\u00e7a e tentar uma chance pelo t\u00edtulo. <br><br>O co-principal ser\u00e1 um confronto bem divertido na divis\u00e3o dos meio-m\u00e9dios, com Santiago Ponzinibio e Carlston Harris se enfrentando em uma luta que provavelmente terminar\u00e1 antes que os jurados se envolvam, o que deve aumentar a expectativa antes de chegarmos ao evento principal.<br><br>As outras lutas do card principal incluem dois confrontos de peso m\u00e9dio, o primeiro entre Abdul Razak Alhassan e Cesar Almeida, e o segundo coloca Chris Curtis contra Roman Kopylov, al\u00e9m de um confronto de peso pena entre o invicto Austin Bashi e o talentoso Christian Rodriguez, e uma luta de peso m\u00e9dio entre Punahele Solano e Uros Medic para abrir o card principal.<br><br>As preliminares est\u00e3o repletas de muitos talentos internacionais, o que significa que as coisas v\u00e3o ser bem divertidas enquanto passamos pelas oito preliminares e seis lutas do card principal desta pr\u00f3xima noite de luta do UFC.<br><br>Voc\u00ea pode verificar todos os\u00a0<a href=\"https:\/\/www.gambyl.com\/pt\/ufc\/\">UFC\/MMA <\/a>apostas, a an\u00e1lise de cada lutador e a aposta final que voc\u00ea pode fazer nessas lutas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: Dern vs Ribas 2 Probabilidades e informa\u00e7\u00f5es do card de luta<\/h2>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><em>Mackenzie Dern 2.525<\/em><\/td><td><em>Amanda Ribas 1.554<\/em><\/td><\/tr><tr><td><em>Santiago Ponzinibbio 1.803<\/em><\/td><td><em>Carlston Harris 1.995<\/em><\/td><\/tr><tr><td><em>Abdul Razak Alhassan 3.285<\/em><\/td><td><em>C\u00e9sar Almeida 1.336<\/em><\/td><\/tr><tr><td><em>Chris Curtis 3.145<\/em><\/td><td><em>Romano Kopylov 1.347<\/em><\/td><\/tr><tr><td><em>Austin Bashi 1.444<\/em><\/td><td><em>Cristiano Rodr\u00edguez 2.754<\/em><\/td><\/tr><tr><td><em>Punahele Soriano 2.576 <\/em><\/td><td><em>Uros Medic 1.511<\/em><\/td><\/tr><tr><td><em>Jos\u00e9 Johnson 11.488<\/em><\/td><td><em>Felipe Bunes 2.631<\/em><\/td><\/tr><tr><td><em>Marco T\u00falio 1.241<\/em><\/td><td><em>Ihor Potieria 3.975<\/em><\/td><\/tr><tr><td><em>Thiago Mois\u00e9s 1.632<\/em><\/td><td><em>Trey Ogden 2.284<\/em><\/td><\/tr><tr><td><em>Preston Parsons 4.615<\/em><\/td><td><em>Jacob Smith 1.19<\/em><\/td><\/tr><tr><td><em>Ernesta Kareckaite 1.414 <\/em><\/td><td><em>Nicolle Caliari 2.944<\/em><\/td><\/tr><tr><td><em>Magomed Gadzhiyasulov 1.333<\/em><\/td><td><em>Bruno Lopes 3.28<\/em><\/td><\/tr><tr><td><em>Vit\u00f3ria Dudakova 4,74<\/em><\/td><td><em>F\u00e1tima Kline 1.188<\/em><\/td><\/tr><tr><td><em>Joe Solecki 5,51<\/em><\/td><td><em>Nurullo Aliev 1.141<\/em><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td><strong>Quando?<\/strong><\/td><td><em>S\u00e1bado, 11 de janeiro, \u00e0s 16h00 ET, 15h00 CST, 14h00 MT e 13h00 PT<\/em><\/td><\/tr><tr><td><strong>Onde?<\/strong><\/td><td><em>UFC Apex, em Las Vegas<\/em><\/td><\/tr><tr><td><strong>Onde posso assistir?<\/strong><\/td><td><a href=\"https:\/\/www.ufcfightpass.com\/\"><em>UFC Fight Pass<\/em><\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Mackenzie Dern x Amanda Ribas<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Mackenzie Dern?<\/strong><br><br>Dern \u00e9 uma das grapplers mais perigosas do UFC no momento. Toda vez que ela leva uma luta para o ch\u00e3o e come\u00e7a a fazer sua magia de BJJ, prendemos a respira\u00e7\u00e3o porque sabemos que ela est\u00e1 a meros segundos de algo insano. <br><br>No entanto, por mais que ela seja incr\u00edvel no ch\u00e3o, ela fica um pouco para tr\u00e1s em outras disciplinas. Sua troca\u00e7\u00e3o \u00e9 um tanto \u00e1spera e sua incapacidade de lutar tamb\u00e9m \u00e9 um preju\u00edzo para ela, \u00e9 algo que a est\u00e1 segurando muito.<br><br>Estamos esperan\u00e7osos de que estamos errados com isso, e neste fim de semana vemos uma vers\u00e3o melhorada de Dern. Historicamente, ela tem lutado para levar as lutas ao ch\u00e3o, um lugar em que ela precisa muito de lutas para vencer. <br><br><strong>Por que apostar em Amanda Ribas?<\/strong><br><br>Ribas tem uma maneira prim\u00e1ria de vencer essa luta, que \u00e9 mant\u00ea-la em p\u00e9 e ser a striker mais r\u00e1pida. Amanda sempre foi uma lutadora vers\u00e1til que se sente confort\u00e1vel n\u00e3o importa onde a luta v\u00e1, mas n\u00e3o h\u00e1 d\u00favidas em nossas mentes de que ela se destacar\u00e1 em p\u00e9 contra Dern.<br><br>Dern no ch\u00e3o \u00e9 um pesadelo at\u00e9 para os melhores lutadores dessa divis\u00e3o, ent\u00e3o duvidamos muito que Ribas v\u00e1 usar seus ic\u00f4nicos hip tosses aqui nessa luta. <br><br>As principais armas que Ribas utilizar\u00e1 s\u00e3o seu boxe r\u00e1pido e talvez alguns chutes no corpo, embora os chutes possam ser um pesadelo se Dern os pegar e tentar uma queda ou uma varredura.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Mackenzie Dern x Amanda Ribas <\/strong><br><br>A \u00fanica for\u00e7a de Dern \u00e9 onde est\u00e1 o problema com Ribas, porque ela \u00e9 uma lutadora muito equilibrada. Ela \u00e9 extremamente completa e tem todos os tipos de t\u00e9cnicas e habilidades em seu arsenal para fazer desta uma luta muito dif\u00edcil para Dern.<br><br>Achamos que a principal dificuldade de Dern \u00e9 o timing dos p\u00e9s contra Ribas. N\u00e3o h\u00e1 guia ou livro que diga a Dern como lidar com Ribas, porque a maneira como Ribas se move \u00e9 como se ela estivesse dan\u00e7ando, com os p\u00e9s leves, jogando as m\u00e3os para mascarar os golpes. Ela \u00e9 \u00f3tima em dominar os sentidos do oponente e dificultar a leitura do que est\u00e1 por vir.<br><br>Foi isso que deu a Ribas a primeira vit\u00f3ria quando os dois se enfrentaram antes, e acreditamos que isso deve acontecer novamente.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Santiago Ponzinibbio vs. Carlston Harris<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Santiago Ponzinibbio?<\/strong><br><br>Ponzinibbio certamente j\u00e1 passou do auge agora. No entanto, na maior parte do tempo, ele luta do mesmo jeito que sempre lutou, alta press\u00e3o, ritmo alto e bastante agressivo, embora n\u00e3o tanto quanto costumava ser devido \u00e0 idade e tal. <br><br>Santiago Ponzinibbio ter\u00e1 uma vantagem not\u00e1vel nos p\u00e9s, ele tem excelentes golpes e usa seu jogo de p\u00e9s e movimenta\u00e7\u00e3o para preparar ataques. Sempre que Ponzinibbio se afasta e faz suas pequenas fintas, voc\u00ea sabe que ele est\u00e1 prestes a lan\u00e7ar algo grande, como um chute na cabe\u00e7a ou uma curta sequ\u00eancia de boxe. <br><br>Ponzinibbio normalmente usa seu wrestling durante suas lutas, embora pensemos que seria algo um pouco perigoso de se fazer, j\u00e1 que Harris \u00e9 um lutador bastante ativo. <br><br><strong>Por que apostar em Carlston Harris?<\/strong><br><br>Harris \u00e9 um lutador um pouco direto, ele quer levar a luta para o ch\u00e3o, envolver o pesco\u00e7o e fazer seu oponente bater ou dormir.<br><br>Ponzinibbio pode ser um pouco dif\u00edcil em p\u00e9, mas se ele tentar uma queda, essa seria a primeira chance de Harris finalizar, como ficou claro quando ele agarrou o pesco\u00e7o de Jeremiah Wells. <br><br>No entanto, dito isso, Harris n\u00e3o tem a melhor defesa ou ataque, seu desempenho deixa muito para a imagina\u00e7\u00e3o e \u00e9 exatamente isso que faria de Ponzinibbio uma grande amea\u00e7a.<br><br><em><strong>An\u00e1lise final das apostas:<\/strong><\/em><strong> Santiago Ponzinibbio vs. Carlston Harris <\/strong><br><br>O poder de Ponzinibbio em suas m\u00e3os ser\u00e1 um grande equalizador nesta luta. Acreditamos genuinamente que quanto mais tempo a luta permanecer em p\u00e9, mais confort\u00e1vel e confiante ele ficar\u00e1 em lan\u00e7ar mais volume. <br><br>O lado bom da press\u00e3o de Ponzinibbio \u00e9 que, como ele se move tanto para frente, isso faria com que Harris iniciasse as quedas com o p\u00e9 atr\u00e1s, e \u00e9 bem mais f\u00e1cil defender quedas como um agressor do que como algu\u00e9m que est\u00e1 sendo pressionado.<br><br>N\u00e3o achamos que Harris tenha muitas chances contra Ponzinibbio, a menos que seja um golpe muito bem cronometrado ou durante uma sequ\u00eancia ca\u00f3tica, porque, embora Santiago ainda seja bom em causar volume, ele diminuiu um pouco o ritmo, mas acreditamos que o veterano levar\u00e1 a vit\u00f3ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Abdul Razak Alhassan x C\u00e9sar Almeida<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Abdul Razak Alhassan?<\/strong><br><br>Alhassan \u00e9 algu\u00e9m que \u00e9 ridiculamente dif\u00edcil de ler apenas por causa de como o UFC o trata, e isso soa estranho, mas as lutas e oponentes que ele enfrenta est\u00e3o quil\u00f4metros \u00e0 frente dele em termos de competi\u00e7\u00e3o, ou o sobrecarregam completamente do ponto de vista estil\u00edstico. Nunca h\u00e1 uma luta realmente justa, at\u00e9 esta, supomos.<br><br>Alhassan \u00e9 um striker poderoso, isso \u00e9 bastante \u00f3bvio, mas ele tamb\u00e9m tem uma s\u00f3lida base de jud\u00f4, e achamos que isso ser\u00e1 fundamental para lidar com Almeida.<br><br>Em p\u00e9, achamos que ser\u00e1 um acordo de poder versus habilidade, onde Alhassan tentar\u00e1 terminar a luta rapidamente por meio de uma curta explos\u00e3o de produ\u00e7\u00e3o agressiva ou ataques singulares fortes. Se isso falhar, ele poderia, pelo menos, colidir com Almeida, travar um clinch e, em seguida, fazer sua coisa de Jud\u00f4. <br><br><strong>Por que apostar em C\u00e9sar Almeida?<\/strong><br><br>Almeida chegou ao jogo do MMA relativamente tarde em sua carreira de esportes de combate. No entanto, at\u00e9 agora \u00e9 justo dizer que ele se saiu muito bem em se adaptar a diferentes estilos, e temos visto ele evoluir como lutador no curto per\u00edodo em que est\u00e1 aqui.<br><br>Almeida \u00e9 um kickboxer fant\u00e1stico, um campe\u00e3o de kickboxing v\u00e1rias vezes em v\u00e1rias organiza\u00e7\u00f5es e competi\u00e7\u00f5es, ele \u00e9 t\u00e3o bom quanto poss\u00edvel. \u00c9 por isso que achamos que Alhassan provavelmente usar\u00e1 seu grappling para obter uma vit\u00f3ria aqui. Dito isso, Almeida absorveu informa\u00e7\u00f5es como uma esponja, ele tem instintos muito bons para voltar a ficar de p\u00e9 e ele conserva seu cardio bem o suficiente para se permitir explodir de volta a ficar de p\u00e9 ap\u00f3s cada tentativa, ent\u00e3o ele nunca fica sem f\u00f4lego depois de ser derrubado como um kickboxer t\u00edpico pode ficar. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Abdul Razak Alhassan x C\u00e9sar Almeida <\/strong><br><br>Almeida n\u00e3o \u00e9 exatamente treinado em defesa de jud\u00f4, ele \u00e9 treinado em defesa de quedas tradicional, single legs, double legs, levantar do ch\u00e3o.<br><br>O jud\u00f4 \u00e9 um animal totalmente diferente de se lidar e, se Alhassan conseguir se impor nessa luta e usar seus golpes para derrubar Almeida e jog\u00e1-lo no ch\u00e3o, achamos que Alhassan tem uma chance razoavelmente s\u00f3lida de vencer a luta.<br><br>Almeida quer manter essa luta em p\u00e9, n\u00e3o h\u00e1 d\u00favidas sobre isso, mas achamos que haver\u00e1 uma eventual tentativa de queda\/trope\u00e7o de Alhassan. No entanto, ele se adapta bem e acreditamos que ele vai encontrar o final durante o round final.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Chris Curtis contra Roman Kopylov<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Chris Curtis?<\/strong><br><br>Curtis \u00e9 um lutador divertido de assistir, mas depois que ele perde, porque cara, ele tu\u00edta como um louco. No entanto, na jaula ele \u00e9 bastante inteligente quando se trata de sua abordagem de luta, se adapta ao estilo de seus oponentes, e sua defesa de queda e habilidade de wrestling permitem que ele corresponda ao que seu oponente est\u00e1 fazendo no ch\u00e3o. Ele \u00e9 excepcionalmente bem treinado. <br><br>O problema com ele \u00e9 que, embora seja completo, ele n\u00e3o se destaca exatamente em um campo espec\u00edfico de combate. Ele \u00e9 um pau para toda obra, mestre de nada, e embora isso seja \u00f3timo para um atleta de alto n\u00edvel, um lutador especialista encontrar\u00e1 uma maneira de expor algu\u00e9m como ele. <br><br>Curtis \u00e9 \u00f3timo em atacar, absorver ataques e ent\u00e3o imediatamente revidar. Espere que ele tente encontrar contra-ataques quando Kopylov estender suas combina\u00e7\u00f5es, esperamos que ele tamb\u00e9m acerte alguns golpes no corpo, um soco direto \u00e0 dist\u00e2ncia no corpo e mudan\u00e7a de n\u00edvel seguido de escava\u00e7\u00e3o no corpo em dist\u00e2ncias mais pr\u00f3ximas.<br><br><strong>Por que apostar em Roman Kopylov?<\/strong><br><br>Kopylov ter\u00e1 uma ligeira vantagem nos p\u00e9s nesta luta, na nossa opini\u00e3o. Isso se deve ao fato de que ele tem uma vasta experi\u00eancia em sambo de combate, e quando voc\u00ea o assiste lutar, voc\u00ea pode ver o qu\u00e3o disciplinado ele \u00e9.<br><br>Roman raramente comete erros em p\u00e9. Ele \u00e9 calculista, mira na parte certa do corpo para subsequentemente abrir mais alvos para novos ataques, ele \u00e9 um assassino e algu\u00e9m que \u00e9 altamente capaz de desmantelar lentamente a guarda quase impenetr\u00e1vel de Curtis. Ele provavelmente far\u00e1 isso sendo um canhoto astuto e lendo o padr\u00e3o de ataque bastante \u00f3bvio de Curtis.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Chris Curtis contra Roman Kopylov <\/strong><br><br>Curtis \u00e0s vezes fica frustrado no meio de uma luta, e podemos ver que ele ficar\u00e1 frustrado nesta luta, j\u00e1 que Kopylov \u00e9 um striker muito mais cl\u00ednico. Ent\u00e3o, \u00e9 prov\u00e1vel que ele coma muitos golpes e talvez n\u00e3o tenha muito a responder por isso.<br><br>Chris tem um boxe maravilhoso, n\u00e3o me entenda mal, seus fundamentos de boxe s\u00e3o fant\u00e1sticos. No entanto, sua guarda alta deixa seu corpo exposto e voc\u00ea deve saber que Kopylov vai explodir o corpo com chutes no in\u00edcio para derrubar essas m\u00e3os.<br><br>Curtis \u00e9 muito bom em ser um boxeador de postura de l\u00e2mina, ele utiliza o jab e a distra\u00e7\u00e3o da m\u00e3o da frente relativamente bem. Quando essa m\u00e3o da frente \u00e9 lan\u00e7ada para fora, sua cabe\u00e7a fica um pouco exposta a um gancho lateral de for\u00e7a ou direto. Achamos que \u00e9 isso que Kopylov tentar\u00e1 fazer, atrair um ataque de m\u00e3o da frente e ent\u00e3o seguir com um gancho de esquerda ou direto de contra-ataque.<br><br>Se isso n\u00e3o funcionar, Kopylov tamb\u00e9m \u00e9 excelente no wrestling quando a situa\u00e7\u00e3o exige, e isso tamb\u00e9m ser\u00e1 um problema em potencial para Curtis.<br><br>Com mais caminhos para a vit\u00f3ria, esperamos que Kopylov saia vitorioso nesta luta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Austin Bashi x Christian Rodriguez<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Austin Bashi?<\/strong><br><br>Bashi vem de uma fant\u00e1stica vit\u00f3ria por finaliza\u00e7\u00e3o no DWCS sobre Dorian Ramos, e o mais impressionante sobre ele \u00e9 sua atividade. Sua primeira luta amadora foi no in\u00edcio de fevereiro de 2020, h\u00e1 5 anos, e ele teve 13 lutas profissionais.<br><br>O conjunto de habilidades de Bashi \u00e9 muito focado em wrestling. Ele constantemente vai para quedas, e se move em um ritmo t\u00e3o fren\u00e9tico que podemos v\u00ea-lo sobrepujando muitos de seus oponentes no futuro. <br><br>No entanto, dito isso, h\u00e1 um toque de energia nervosa ou ansiosa no primeiro round, onde ele est\u00e1 jogando tudo. Nada al\u00e9m de socos pesados e oscilantes no topo, seguidos por mudan\u00e7as r\u00e1pidas de n\u00edvel, tantas coisas diferentes que s\u00e3o usadas para sobrecarregar seu oponente. Mesmo que pare\u00e7a bagun\u00e7ado \u00e0s vezes, \u00e9 eficaz e leva seu oponente a ter pequenas aberturas nas quais ele pode obter uma queda com sucesso e uma posi\u00e7\u00e3o de reten\u00e7\u00e3o s\u00f3lida.<br><br>Uma coisa que amamos sobre Bashi \u00e9 o qu\u00e3o grudento ele \u00e9 para seus oponentes. Ele n\u00e3o gosta de separar ou criar dist\u00e2ncia durante os momentos de luta. Ele \u00e9 t\u00e3o bom em ficar perto e ser apenas um objeto pesado, pesado para seus oponentes segurarem.<br><br><strong>Por que apostar em Christian Rodriguez?<\/strong><br><br>Rodriguez provavelmente vai ficar doente e cansado desses lutadores em breve. Ele lutou com alguns lutadores incr\u00edveis como Rosas Jr e Isaac Dulgarian, ent\u00e3o ele sem d\u00favida est\u00e1 preparado para esse tipo de luta, mas agora ele est\u00e1 de volta ao fogo depois de uma derrota por finaliza\u00e7\u00e3o dif\u00edcil contra Erosa. <br><br>O melhor sobre Rodriguez \u00e9 que seu cardio \u00e9 fant\u00e1stico. Ele pode nadar com os tubar\u00f5es, sair por cima e lidar com o ritmo insano que os lutadores costumam utilizar em suas lutas. No entanto, com cada novo oponente, v\u00eam novos desafios, e achamos que uma das coisas mais perigosas sobre Bashi s\u00e3o as inc\u00f3gnitas e o fato de que ele \u00e9 um dos prospectos mais jovens a se juntar ao UFC. Ent\u00e3o, ele vai sair com fogo extra sob ele, querendo continuar essa r\u00e1pida ascens\u00e3o ao topo. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Austin Bashi x Christian Rodriguez <\/strong><br><br>Bashi testar\u00e1 a defesa de quedas e a coragem de Rodriguez durante esta luta.<br><br>Rodriguez j\u00e1 esteve aqui antes, ele lutou com jovens lutadores. Ele treinou para muitas dessas lutas e tem melhorado consistentemente por causa disso, e n\u00f3s realmente achamos que ele vai se sair muito bem nessa luta.<br><br>Quando chegarmos ao segundo round, esperamos que Rodriguez continue avan\u00e7ando nas cartas dos jurados e garanta a vit\u00f3ria. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Punahele Soriano x Uros Medic<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Punahele Soriano?<\/strong><br><br>Soriano \u00e9 um cara dif\u00edcil de se falar positivamente, porque embora ele tenha participado de algumas lutas incr\u00edveis no UFC, ele tamb\u00e9m recebeu algumas surras nojentas. Nunca \u00e9 uma coisa boa ver algu\u00e9m aguentar firme porque seu queixo \u00e9 muito dur\u00e1vel. <br><br>Como o queixo de Soriano \u00e9 t\u00e3o dur\u00e1vel, ele n\u00e3o usa exatamente muitas camadas defensivas para evitar danos. Nunca h\u00e1 muito trabalho de p\u00e9s ou movimento de cabe\u00e7a, sua concha, embora existente, est\u00e1 l\u00e1 apenas para que ele possa retornar o fogo imediatamente.<br><br>Uma coisa que sempre estar\u00e1 do lado de Soriano \u00e9 sua tenacidade. Ele est\u00e1 na luta at\u00e9 n\u00e3o estar mais e vai atirar de volta com tudo em seu tanque de gasolina enquanto a luta continuar.<br><br><strong>Por que apostar no Uros Medic?<\/strong><br><br>Medic \u00e9 um lutador incr\u00edvel para ficar de olho, e uma vit\u00f3ria sobre Soriano vai ficar muito boa em seu hist\u00f3rico. Ele \u00e9 um sniper quando luta, seus socos de dist\u00e2ncia e teeps no corpo s\u00e3o lindos de assistir, e todos eles v\u00eam de seu jogo de p\u00e9s e sua habilidade de encontrar \u00e2ngulos. <br><br>Falando em encontrar \u00e2ngulos, seu nocaute sobre Means \u00e9 evid\u00eancia de qu\u00e3o r\u00e1pido ele pensa e planeja um ataque. Means mergulhou para o lado direito de Medic, reiniciou, ent\u00e3o mergulhou novamente para o mesmo lado, apenas para Medic encontrar o queixo com um uppercut de esquerda perfeito. <br><br>\u00c9 isso que Medic deve usar, sua acuidade visual e tamb\u00e9m seu timing, porque Soriano tem leves problemas defensivos e se sua cabe\u00e7a for exposta a um golpe forte, pode apostar que Uros disparar\u00e1 aquele m\u00edssil de esquerda e o far\u00e1 acertar o alvo.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Punahele Soriano x Uros Medic <\/strong><br><br>Voltando ao fato de que Soriano leva bastante soco, isso n\u00e3o \u00e9 um bom press\u00e1gio considerando a precis\u00e3o incrivelmente alta dos golpes de Medic, assim como o fato de que seus socos tamb\u00e9m s\u00e3o bem pesados. Uma leve gra\u00e7a salvadora para Punahele \u00e9 sua experi\u00eancia em wrestling, e suspeitamos que quando a press\u00e3o aumentar, ele vai depender de quedas e controle para tentar controlar Medic.<br><br>Uma pequena preocupa\u00e7\u00e3o para Medic \u00e9 seu cardio. Ele nunca levou uma luta \u00e0 dist\u00e2ncia, e embora seja incr\u00edvel ouvir isso, tamb\u00e9m \u00e9 talvez um pouco preocupante se Soriano utilizar seu wrestling e conseguir uma vit\u00f3ria por decis\u00e3o, porque essa \u00e9 a \u00fanica maneira de realmente vermos Uros perdendo.<br><br>Ainda assim, achamos que o Medic vai encontrar o golpe e nocaute\u00e1-lo durante a luta, possivelmente na metade do caminho.<\/p>\n\n\n\n<div id=\"advad-gambyl-3584378638\" class=\"house advad-gambyl-third-paragraph advad-gambyl-entity-placement\" style=\"margin-top: 10px;margin-right: 10px;margin-bottom: 10px;margin-left: 10px;clear: both;\" data-cfpa=\"31717\" data-cfpw=\"31717\"><h2><strong><span style=\"color:#F0BE00;font-weight:800;\">Aten\u00e7\u00e3o novos jogadores!<\/span><\/strong><\/h2>\r\n\t<img src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA4MDAgMTk3IiB3aWR0aD0iODAwIiBoZWlnaHQ9IjE5NyIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDI0JTJGMDclMkZHYW1ieWxfZ29sZF9sb2dvcy13aGl0ZS1zcGFuaXNoLTEucG5nIiBkYXRhLXc9IjgwMCIgZGF0YS1oPSIxOTciIGRhdGEtYmlwPSIiPjwvc3ZnPg==\" data-spai=\"1\" alt=\"Gambyl\" width=\"125\" height=\"36\">\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Aposte em esportes legalmente na Bolsa de Apostas Gambyl. Oferta para novos jogadores: $10 USD para todas as novas contas verificadas, mais um b\u00f4nus de 100% no seu primeiro dep\u00f3sito.<\/a><\/p>\t\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Junte-se hoje!<\/a><\/p>\r\n<\/div><br style=\"clear: both; display: block; float: none;\"\/><script type=\"text\/javascript\">;new advadsCfpAd( 31717 );<\/script><h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Jos\u00e9 Johnson vs. Felipe Bunes<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Jos\u00e9 Johnson?<\/strong><br><br>Johnson vem de um ciclo de vit\u00f3rias e derrotas, com sua luta mais recente terminando em derrota contra Asu Almabayev. Foi uma luta bem dura para Jos\u00e9 porque ele teve que lidar com um wrestler de press\u00e3o pesada que conseguiu control\u00e1-lo por 11 minutos, ent\u00e3o nunca chegamos a ver muito do que ele preparou durante aquele camp. <br><br>Johnson sempre foi um striker muito habilidoso. Seu alcance e comprimento como lutador t\u00eam sido um grande desafio para alguns de seus oponentes descobrirem. Embora sua fraqueza seja claramente seu contra-wrestling, ele frequentemente tem as ferramentas certas no arsenal para tornar o wrestling dif\u00edcil de iniciar, j\u00e1 que seus oponentes t\u00eam que lidar com os golpes antes de entrar em uma posi\u00e7\u00e3o de queda. <br><br>Agora, Johnson \u00e9 incrivelmente alto para a divis\u00e3o, e isso lhe d\u00e1 uma vantagem \u00fanica em acertar joelhadas no meio ou no clinch de forma bastante eficaz. O melhor sobre Johnson \u00e9 que, devido ao seu campo de treinamento para Almabayev, seu contra-wrestling deveria ter melhorado, e ainda mais durante este campo, enquanto ele arrumava as coisas.<br><br><strong>Por que apostar em Felipe Bunes?<\/strong><br><br>Bunes tem apenas uma luta no UFC e, embora tenha sido uma derrota para Joshua Van, ele sem d\u00favida ganhou muita experi\u00eancia, j\u00e1 que Van \u00e9 um dos pesos-mosca mais perigosos do momento.<br><br>Felipe \u00e9 um lutador completo que \u00e9 r\u00e1pido para mudar de estilo e conseguir quedas se precisar, mas uma coisa que queremos destacar aqui \u00e9 sua guarda. Ele \u00e9 muito bom em cobrir frouxamente a parte superior do tronco e permitir a mitiga\u00e7\u00e3o de danos \u00e0 cabe\u00e7a, mas isso deixa seu corpo exposto a ataques. N\u00f3s realmente achamos que, no in\u00edcio, se Johnson for inteligente, ele empregar\u00e1 teeps no corpo para abaixar essas m\u00e3os antes de come\u00e7ar a usar seus golpes de boxe para atacar a cabe\u00e7a.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Jos\u00e9 Johnson vs. Felipe Bunes <\/strong><br><br>Desta vez, podemos ver um desafio semelhante para Johnson, j\u00e1 que Bunes \u00e9 bastante focado na luta agarrada quando luta, embora talvez n\u00e3o na mesma extens\u00e3o ou n\u00edvel de habilidade que Almabayev.<br><br>Esperamos um Johnson nivelado, algu\u00e9m que possa lidar com grapplers muito melhor agora e, acima de tudo, muita atividade no clinch. Seus joelhos s\u00e3o incrivelmente ativos e \u00f3timos para causar dano ao corpo de seus oponentes.<br><br>Bunes tem um boxe decente. Ele come\u00e7a com a m\u00e3o da frente e isso pode ser um pouco f\u00e1cil de ler, mas o problema que vemos ele enfrentando \u00e9 ceder \u00e0 press\u00e3o de Johnson. Ele recua bastante e se Jos\u00e9 usar seu alcance efetivamente, ele pode sufocar um pouco o movimento de Felipe simplesmente usando seu jab, mantendo as armas longas ativas e certificando-se de que as costas de Bunes estejam contra a grade.<br><br>Tudo isso faz com que Johnson tenha a m\u00e3o levantada no final da luta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Marco Tulio vs. Ihor Potieria<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Marco Tulio?<\/strong><br><br>Tulio tem sido uma for\u00e7a de destrui\u00e7\u00e3o durante sua ascens\u00e3o \u00e0 vit\u00f3ria no DWCS, derrotando muitos de seus oponentes por nocautes limpos que resultaram de combina\u00e7\u00f5es curtas e afiadas nos p\u00e9s. Ele \u00e9 incrivelmente perigoso nos p\u00e9s. <br><br>Tulio vem da Chute Boxe, uma das academias mais importantes do Brasil, ent\u00e3o voc\u00ea sabe que ele est\u00e1 recebendo um treinamento de alto n\u00edvel. Isso mostra que quando ele luta, tudo \u00e9 tranquilo e bem cronometrado. Quer dizer, ele est\u00e1 enfrentando Poti\u00e9ria, algu\u00e9m que n\u00e3o \u00e9 particularmente bem qualificado, ent\u00e3o esperamos que ele se saia excepcionalmente bem.<br><br><strong>Por que apostar em Ihor Potieria?<\/strong><br><br>Potieria \u00e9 um cara dif\u00edcil de realmente ficar animado porque, vez ap\u00f3s vez, seu queixo foi testado e seu pesco\u00e7o foi estrangulado. Houve tantos momentos durante sua carreira no UFC em que ele parecia razoavelmente bom, mas tamb\u00e9m bastante falho, j\u00e1 que a durabilidade de seu queixo \u00e9 uma grande preocupa\u00e7\u00e3o. Seu wrestling, embora explosivo, s\u00f3 pode vir em rajadas curtas, j\u00e1 que seu cardio n\u00e3o \u00e9 constru\u00eddo para queda ap\u00f3s queda. <br><br>O padr\u00e3o de Potieria parece ser bastante repetitivo tamb\u00e9m, ele tem a mesma postura, o mesmo visual, e enquanto seus golpes podem ser ligeiramente variados. Todos eles come\u00e7am do mesmo jeito, atrav\u00e9s de um ataque de m\u00e3o da frente. Muitas vezes ele tenta um \u00fanico direto de esquerda ou algo assim, mas \u00e9 muito pouco comparado com suas rajadas.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Marco Tulio vs. Ihor Potieria <\/strong><br><br>Todos os pontos fortes de T\u00falio n\u00e3o s\u00e3o um bom press\u00e1gio contra algu\u00e9m como Poti\u00e9ria, que parece s\u00f3 aceitar lutas porque precisa de dinheiro ou algo assim. <br><br>Dito isso, como em qualquer luta que envolva duas pessoas que podem dar um soco e um chute, pode haver um momento em meio ao caos em que Potieria balan\u00e7a e balan\u00e7a o rec\u00e9m-chegado. No entanto, como a defesa de Potieria \u00e9 tipicamente baseada em movimento e nada mais, n\u00e3o achamos que Tulio ter\u00e1 muitos problemas para encontrar seu alvo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Thiago Mois\u00e9s vs. Trey Ogden<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Thiago Mois\u00e9s?<\/strong><br><br>Moises tem sido um lutador incrivelmente perigoso, muito completo, mas realmente, realmente se destaca no ch\u00e3o. Essa vai ser a coisa mais fascinante nessa luta, j\u00e1 que Ogden \u00e9 muito pesado no wrestling quando luta.<br><br>Moises esteve no cage com alguns dos mais perigosos Lightweights do plantel. Embora ele ainda n\u00e3o tenha estado na disputa pelo t\u00edtulo, ele tem sido um gatekeeper perfeito para a divis\u00e3o. <br><br>Uma coisa que achamos um pouco subestimada \u00e9 sua habilidade de golpear, ele \u00e9 bem diverso na forma como pode causar dano em p\u00e9. Ele \u00e9 um pouco padr\u00e3o \u00e0s vezes, mas seus ataques v\u00eam de ambas as posturas ou de ambos os lados, ent\u00e3o se Ogden n\u00e3o conseguir derrubar, ele ter\u00e1 que lidar com algu\u00e9m que pode n\u00e3o ser muito pesado em volume com seus golpes, mas ainda assim tem um bom soco. <br><br><strong>Por que apostar em Trey Ogden?<\/strong><br><br>Ogden \u00e9 talvez um dos desafios mais \u00fanicos para Moises porque ele \u00e9 bastante unidimensional com seu conjunto de habilidades. Ele \u00e9 um especialista em submiss\u00e3o e prospera nas lutas mais dif\u00edceis.<br><br>Agora, o interessante, pelo menos de um ponto de vista estat\u00edstico, \u00e9 que Ogden nunca foi derrubado antes, mas Moises foi. N\u00e3o podemos deixar de pensar que Ogden acabar\u00e1 no controle superior porque ele \u00e9 muito bom em derrubar.<br><br>Nossa preocupa\u00e7\u00e3o \u00e9 se ele consegue acompanhar a habilidade de grappling de Moises. N\u00f3s realmente achamos que este \u00faltimo parecer\u00e1 muito confort\u00e1vel no ch\u00e3o, mas como em qualquer luta de wrestler versus grappler, o wrestler tende a ser o que tem mais controle.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Thiago Mois\u00e9s vs. Trey Ogden <\/strong><br><br>Qualquer momento no ch\u00e3o com Moises \u00e9 tenaz, pois seu grappling \u00e9 de primeira linha. Embora pensemos que Ogden ser\u00e1 capaz de sobreviver \u00e0 maioria das tentativas de submiss\u00e3o, ele ainda vai se mover, se adaptar e trocar de posi\u00e7\u00e3o constantemente.<br><br>A garra de Ogden ser\u00e1 muito importante para vencer Moises, nunca o deixe se acomodar e calcular seu pr\u00f3ximo movimento. Precisa ser uma a\u00e7\u00e3o ininterrupta e, se alguma coisa, Ogden \u00e9 certamente um desses lutadores que pode for\u00e7ar esse ritmo.<br><br>A quest\u00e3o para essa luta \u00e9 se Trey ser\u00e1 capaz de controlar seu oponente, um especialista em BJJ faixa-preta que aceita qualquer queda porque se sente confort\u00e1vel no ch\u00e3o. <br><br>Ogden \u00e9 bom o suficiente para bloquear finaliza\u00e7\u00f5es da guarda? Claro, mas Moises \u00e9 certamente algu\u00e9m muito, muito diferente. E acreditamos que ele estar\u00e1 melhor conforme a luta for mais longa, e isso provavelmente dar\u00e1 a vit\u00f3ria a Thiago.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Preston Parsons contra Jacobe Smith<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Preston Parsons?<\/strong><br><br>Parsons vem de uma luta um tanto mon\u00f3tona contra Oban Elliott, na qual, embora ambos os lutadores tenham usado golpes fortes e frequentes, nada acertou efetivamente.<br><br>Supomos que \u00e9 isso que acontece quando dois lutadores brincam em p\u00e9. \u00c9 basicamente assim que Parsons luta, ele \u00e9 um lutador de alto volume que normalmente n\u00e3o joga muito para cima. Ele geralmente \u00e9 direto e estreito quando se trata de seu plano de jogo, constantemente avan\u00e7ando e ca\u00e7ando aquela queda para que ele possa trabalhar no controle de seu oponente e talvez abri-lo para a submiss\u00e3o.<br><br>Parsons nunca foi um striker, ele conhece os fundamentos do MMA, mas no geral n\u00e3o deve ser uma grande amea\u00e7a para Smith em p\u00e9. Seu principal trunfo para essa luta \u00e9 seu estilo de wrestling de press\u00e3o e volume absoluto em tentativas de queda. No entanto, fora isso, ele n\u00e3o \u00e9 nada particularmente especial.<br><br><strong>Por que apostar em Jacobe Smith?<\/strong><br><br>Smith \u00e9 definitivamente algu\u00e9m que persegue a a\u00e7\u00e3o onde quer que a luta aconte\u00e7a. Seja no ch\u00e3o ou em p\u00e9, ele avan\u00e7a com uma agressividade incr\u00edvel e sempre persegue um final, e \u00e9 por isso que sua taxa de finaliza\u00e7\u00e3o \u00e9 t\u00e3o espetacularmente alta. <br><br>Agora, embora o que acabamos de dizer pare\u00e7a um elogio, tamb\u00e9m leva a alguma preocupa\u00e7\u00e3o geral. N\u00f3s nos perguntamos se ele conseguir\u00e1 ter o tanque de gasolina para manter esse tipo de estilo e press\u00e3o por um longo per\u00edodo de tempo, j\u00e1 que Parsons pode ser bem dur\u00e1vel.<br><br>Seis de suas nove lutas terminaram no primeiro round, ele foi at\u00e9 o fim duas vezes, e se pudermos refletir sobre sua luta contra Lewis no Fury FC por um momento, essa luta foi incrivelmente pesada de luta livre de ambos os lados. Raramente houve um momento de golpes antes que algu\u00e9m tentasse outra queda, e assim mais 2 a 3 minutos de nada al\u00e9m de chaves de corpo firmes e movimentos posicionais constantes. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Preston Parsons contra Jacobe Smith<\/strong><br><br>A press\u00e3o de Parsons ser\u00e1 a principal &quot;vantagem&quot; sobre Smith, e colocamos a vantagem entre aspas por um motivo espec\u00edfico. Isso \u00e9 simplesmente porque acreditamos que a defesa de queda de Smith \u00e9 melhor do que as pessoas esperam devido ao treinamento na AKA, uma academia que \u00e9 repleta de excelentes lutadores de classe mundial. <br><br>A luta de Smith com o Fury FC teve um ritmo brutal e ele ainda permaneceu como o lutador mais efetivo que acertou socos pesados nas posi\u00e7\u00f5es em p\u00e9, apesar da fadiga. Se sua durabilidade est\u00e1 nos dizendo alguma coisa, \u00e9 que essa luta vai ser um 3 rounds exaustivo com muito wrestling envolvido.<br><br>Acreditamos que Smith tem a vantagem tanto de encontrar um final r\u00e1pido quanto de ter coragem para lutar por uma longa luta.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Ernesta Kareckaite x Nicolle Caliari<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Ernesta Kareckaite?<\/strong><br><br>Kareckaite vai ter uma vantagem de tamanho muito not\u00e1vel sobre Caliare. Ela \u00e9 muito, muito alta e longa para a divis\u00e3o e isso normalmente vai apresentar desafios \u00fanicos para suas oponentes.<br><br>Ela sempre foi uma striker bastante visceral, lan\u00e7ando volume para baixo alcance e nunca dando realmente ao seu oponente muito descanso na a\u00e7\u00e3o. \u00c9 sempre uma barragem constante de golpes que v\u00eam com muito poder e alguma seguran\u00e7a devido \u00e0 sua vantagem de alcance. <br><br>O que n\u00e3o gostamos muito sobre o golpe de Kareckaite \u00e9 como ela ainda \u00e9 um alvo enorme para contra-ataques. Ela lidera um pouco com a cabe\u00e7a devido \u00e0 sua vantagem de altura, e \u00e9 algo que seu oponente anterior, Barbosa, exp\u00f4s de certa forma, e isso \u00e9 apenas por estar disposto a golpear Kareckaite. <br><br>Quanto mais tempo essa luta permanecer em p\u00e9, mais confian\u00e7a Kareckaite ter\u00e1, mais combina\u00e7\u00f5es fortes ela conseguir\u00e1 fazer e mais confort\u00e1vel ela estar\u00e1 no oct\u00f3gono. <br><br>Uma coisa que foi comentada por outros \u00e9 a defesa de Kareckaites no grappling. Ela \u00e9 muito, muito defensivamente s\u00f3lida no ch\u00e3o, e parte disso vem do seu treinamento, mas uma grande parte vem do seu comprimento. Quanto mais longo um lutador \u00e9, mais dif\u00edcil pode ser prend\u00ea-lo em uma posi\u00e7\u00e3o por um longo per\u00edodo de tempo. <br><br><strong>Por que apostar em Nicolle Caliari?<\/strong><br><br>Nicolle Caliari vem de uma fant\u00e1stica vit\u00f3ria por finaliza\u00e7\u00e3o no DWCS, embora tenha vencido uma lutadora de 35 anos, o que definitivamente deixa uma marca forte no resultado. <br><br>Caliari \u00e9 faixa preta em BJJ e isso foi demonstrado durante sua luta no DWCS, na qual ela se adaptou de sua posi\u00e7\u00e3o inferior para encontrar um armlock e travar aquele ot\u00e1rio com for\u00e7a. No entanto, nossa principal preocupa\u00e7\u00e3o \u00e9 sua troca\u00e7\u00e3o. Ela \u00e9 \u00f3tima em ser agressiva, mas lidera com o queixo e isso \u00e9 um grande sinal de alerta, considerando que Kareckaite \u00e9 uma striker t\u00e3o perigosa que ter\u00e1 uma vantagem enorme de alcance sobre o grappler. <br><br>Ela parece ser uma especialista tradicional em arremessos de jud\u00f4, BJJ, que efetivamente n\u00e3o quer nada mais do que levar a luta para o ch\u00e3o. Ela com certeza vai ter que levar a luta para o ch\u00e3o para acabar com qualquer vantagem que Kareckaite tenha, mas ela precisa fazer isso de uma posi\u00e7\u00e3o que v\u00e1 facilmente levar a uma submiss\u00e3o. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Ernesta Kareckaite x Nicolle Caliari <\/strong><br><br>Kareckaite sem d\u00favida ser\u00e1 a striker mais efetiva nesta luta. Ela prospera em p\u00e9, e suspeitamos que ela ter\u00e1 dificuldades no in\u00edcio para obter as leituras defensivas nas tentativas de queda de Caliare. Achamos que, quanto mais a luta durar, mais f\u00e1cil ser\u00e1 para Kareckaite evitar completamente essas quedas, e apenas usar seu boxe para causar dano contra a artista de finaliza\u00e7\u00e3o.<br><br>Depois de assistir \u00e0 luta de Calipari contra Laframboise, no entanto, ficamos um pouco preocupados que as finaliza\u00e7\u00f5es sejam sua \u00fanica maneira de vencer essa luta, j\u00e1 que ela estava efetivamente perdendo o primeiro round por n\u00e3o conseguir manter uma posi\u00e7\u00e3o s\u00f3lida por muito tempo. Aquele armlock foi uma gra\u00e7a salvadora para ela.<br><br>Acreditamos que Caliari n\u00e3o ter\u00e1 o mesmo sucesso da \u00faltima vez e acreditamos que Kareckaite dominar\u00e1 a luta at\u00e9 conseguir uma vit\u00f3ria por decis\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Magomed Gadzhiyasulov x Bruno Lopes<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Magomed Gadzhiyasulov?<\/strong><br><br>Gadzhiyasulov tem sido uma adi\u00e7\u00e3o bastante divertida ao elenco dos meio-pesados, usando um ritmo de luta pesado e um kickboxing excepcional para desgastar completamente seus oponentes.<br><br>Em p\u00e9, Gadzhiyasulov luta de forma bem solta, sua postura \u00e9 a de um kickboxer tradicional, mas ele tem velocidade e capacidade atl\u00e9tica para mudar de n\u00edvel e lutar quando necess\u00e1rio.<br><br>Uma coisa importante que voc\u00ea notar\u00e1 ao assistir Gadzhiyasulov lutar \u00e9 que ele \u00e9 muito r\u00e1pido com seus chutes. Seus chutes s\u00e3o, sem d\u00favida, uma das partes mais fortes de seu jogo de troca\u00e7\u00e3o.<br><br>No entanto, ele s\u00f3 se sente confort\u00e1vel na dist\u00e2ncia de chutes, porque quando est\u00e1 na dist\u00e2ncia de boxe, na qual pode receber ganchos ou uppercuts, ele tende a ser atingido com frequ\u00eancia, apenas porque suas defesas dependem muito de distanciamento e movimento. <br><br>Agora, seu wrestling \u00e9 muito, muito bom, seu controle superior, sua habilidade de manobrar no ch\u00e3o para entrar em posi\u00e7\u00f5es nas quais ele pode aplicar ground and pound ou se esgueirar para uma posi\u00e7\u00e3o de submiss\u00e3o \u00e9 sublime, e ele pode fazer isso por tr\u00eas rounds sem muitos sinais de fadiga. <br><br><strong>Por que apostar em Bruno Lopes?<\/strong><br><br>Lopes \u00e9 apenas um rebatedor pesado e brutal, seu poder de soco pode apresentar alguns problemas para Gadzhiyasulov, e embora ele n\u00e3o tenha o trabalho de p\u00e9s ou a velocidade para acompanhar a leveza de Gadzhiyasulov, ele tem chutes nas pernas realmente fortes que ser\u00e3o absolutamente essenciais para tirar a mobilidade do lutador mais r\u00e1pido, Gadzhiyasulov, e, no final das contas, permitir\u00e3o que Lopes cace seu alvo com um pouco mais de facilidade. <br><br>Agora, em termos de velocidade e capacidade atl\u00e9tica, Gadzhiyasulov ser\u00e1 o lutador muito mais m\u00f3vel, aquele que provavelmente iniciar\u00e1 muitas sequ\u00eancias de golpes, e tamb\u00e9m temos a sensa\u00e7\u00e3o de que o ataque de luta livre de Gadzhiyasulov s\u00f3 aumentar\u00e1 esse ataque e atividade avassaladora com os quais Lopes ter\u00e1 que se preocupar e tentar conter. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Magomed Gadzhiyasulov x Bruno Lopes <\/strong><br><br>Estamos intrigados para ver se Gadzhiyasulov desenvolveu algum tipo de defesa de chute nas pernas porque Lopes n\u00e3o tem medo de atacar as pernas no in\u00edcio, ele tem chutes nas pernas muito fortes e sua postura ortodoxa \u00e9 perfeita para possivelmente replicar o mesmo dano que Ribeiro aplicou no in\u00edcio da luta, o que vimos afetar muito Gadzhiyasulov.<br><br>Esta \u00e9 uma luta entre dois meio-pesados extremamente poderosos que ainda s\u00e3o novos no UFC e que est\u00e3o tentando se afirmar na divis\u00e3o, ent\u00e3o \u00e9 prov\u00e1vel que vejamos alguns confrontos muito pesados e excelentes trocas, resultando em alguns momentos emocionantes.<br><br>Aquele que tem mais chances de vencer aqui \u00e9 Gadzhiyasulov, devido ao seu conjunto diversificado de habilidades, bem como sua capacidade de misturar os estilos rapidamente. Suas quedas e habilidade de luta livre provavelmente ser\u00e3o o maior conjunto de habilidades que levaria a uma vit\u00f3ria aqui. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Victoria Dudakova x F\u00e1tima Kline<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Victoria Dudakova?<\/strong><br><br>Dudakova \u00e9 uma lutadora bem interessante, ela est\u00e1 lentamente se tornando uma lutadora muito completa, mas ainda n\u00e3o sabemos se ela \u00e9 uma lutadora de n\u00edvel UFC.<br><br>Ela \u00e9 muito uniforme com seus golpes, n\u00e3o \u00e9 nada muito incr\u00edvel, nem muito t\u00e9cnico, s\u00e3o apenas golpes limpos, padronizados e bem cronometrados, e na maioria das vezes, eles funcionam efetivamente, mas quando as lutas ficam um pouco dif\u00edceis e seu oponente morde o protetor bucal e joga todos os golpes limpos e l\u00f3gicos pela janela, Dudakova tende a ter dificuldade para acompanhar.<br><br>Essa \u00faltima n\u00e3o \u00e9 exatamente uma grande preocupa\u00e7\u00e3o, j\u00e1 que Kline \u00e9, em geral, uma lutadora de alcance f\u00edsico muito pr\u00f3ximo, que utiliza o controle do corpo e a luta livre para exaurir sua oponente a ponto de uma finaliza\u00e7\u00e3o poder aparecer. <br><br>Dito isso, Dudakova n\u00e3o \u00e9 apenas uma striker, ela aos poucos adicionou alguns instintos de luta livre ao seu arsenal, sendo a principal respons\u00e1vel por iniciar quedas e, se ela falhar nessa queda, ela \u00e9 relativamente boa em lidar com o oponente.<br><br><strong>Por que apostar em Fatima Kline?<\/strong><br><br>Kline \u00e9 uma lutadora tremenda, altamente capaz de intimidar qualquer um de seus oponentes e, embora tenha perdido para Jasudavicius em sua estreia, costumamos dizer que uma estreia contra um grande talento como Jasudavicius \u00e9 um presente para qualquer novato, pois eles t\u00eam a oportunidade de vivenciar um alto n\u00edvel de competi\u00e7\u00e3o.<br><br>Kline \u00e9 fant\u00e1stica em usar suas fintas para mascarar seus ataques, ela est\u00e1 sempre se movendo e mudando seus \u00e2ngulos e, no geral, \u00e9 um alvo muito dif\u00edcil de ser lido, e isso vai jogar a seu favor nesta luta, pois \u00e9 um pouco diferente em compara\u00e7\u00e3o com as oponentes anteriores de Dudakova no UFC. <br><br>Kline n\u00e3o tem medo de a\u00e7\u00e3o, ela busca causar dano \u00e0 oponente por meio de combina\u00e7\u00f5es de boxe e um chute forte no corpo, e como Dudakova tem um cardio um tanto duvidoso ap\u00f3s a primeira metade da luta, sentimos que esses chutes fortes s\u00f3 v\u00e3o acentuar o problema cardiovascular e, assim, manter o ritmo do lado de Kline. <br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Victoria Dudakova x F\u00e1tima Kline <\/strong><br><br>Dudakova tem uma chance bastante s\u00f3lida de vencer esta luta se ela permanecer de p\u00e9, usando movimentos r\u00e1pidos para ficar fora do alcance dos ataques de luta livre de Kline e usando seus pr\u00f3prios ataques de longo alcance para causar dano. <br><br>Como Kline \u00e9 basicamente uma lutadora, provavelmente veremos press\u00e3o constante dela, mas achamos que Dudakova \u00e9 \u00f3tima em lan\u00e7ar ataques de boxe de forma consistente o suficiente para manter Kline um pouco afastado. <br><br>O wrestling de Kline \u00e9 muito, muito bom, e ela tem o cardio para lutar por um longo per\u00edodo de tempo, ao contr\u00e1rio de Dudakova, ent\u00e3o quanto mais longo for esse round, melhor as coisas ficar\u00e3o para Kline, e achamos que essa luta ir\u00e1 para os placares dos ju\u00edzes e favorecer\u00e1 Fatima Kline com a vit\u00f3ria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">UFC Fight Night: <strong>Joe Solecki contra Nurullo Aliev<\/strong><\/h2>\n\n\n\n<p><strong>Por que apostar em Joe Solecki?<\/strong><br><br>Solecki est\u00e1 chegando nesta luta como um lutador substituto de \u00faltima hora e, embora ele possa apresentar alguns desafios \u00fanicos contra o agressivo Aliev, n\u00e3o temos muita certeza se ele ser\u00e1 capaz de lidar com o ataque de quedas.<br><br>Solecki tem um BJJ muito, muito bom e tem algumas \u00f3timas finaliza\u00e7\u00f5es em seu hist\u00f3rico, mas sempre teve uma baixa porcentagem de defesa de quedas, t\u00edpica de algu\u00e9m que \u00e9 principalmente um especialista em finaliza\u00e7\u00f5es. Ele incentiva as quedas para poder estar em qualquer posi\u00e7\u00e3o no ch\u00e3o e atacar seus oponentes com tentativas de finaliza\u00e7\u00e3o.<br><br><strong>Por que apostar em Nurullo Aliev?<\/strong><br><br>Aliev vem de uma luta bastante decente contra Alves h\u00e1 dois anos, na qual o vimos fazer o que sempre faz, lutar e parecer muito no controle durante grande parte da luta. <br><br>Aliev n\u00e3o passa de um lutador. \u00c0s vezes, ele desfere socos fortes e selvagens quando a luta est\u00e1 em p\u00e9, mas, no fim das contas, seu objetivo principal \u00e9 tentar uma queda e se firmar como um lutador dominante, utilizando press\u00e3o superior e pressionando o oponente at\u00e9 que o ground and pound comece.<br><br>N\u00e3o nos entenda mal, a troca\u00e7\u00e3o de Aliev \u00e9 relativamente boa, ele \u00e9 muito r\u00e1pido com seus movimentos e tem um estilo descolado que o faz parecer agitado e explosivo, mas na verdade \u00e9 s\u00f3 para que ele possa mascarar a queda ou um ataque r\u00e1pido por cima, sabe, as coisas t\u00edpicas que vemos em lutadores de sambo.<br><br><em><strong>An\u00e1lise final das apostas: <\/strong><\/em><strong>Joe Solecki contra Nurullo Aliev<\/strong><br><br>Os golpes de Aliev s\u00f3 s\u00e3o eficazes por causa dessa amea\u00e7a de queda, e a \u00fanica maneira real de anular esse tipo de movimento e prepara\u00e7\u00e3o \u00e9 golpeando primeiro e interrompendo esse ritmo, o que n\u00e3o vemos Solecki fazendo com grande sucesso, a menos que ele utilize um plano de jogo de ir com tudo no in\u00edcio devido \u00e0 sua falta de prepara\u00e7\u00e3o para essa luta.<br><br>Esse confronto \u00e9 \u00f3timo para Aliev porque seu \u00faltimo oponente foi algu\u00e9m que tentou a mesma finaliza\u00e7\u00e3o v\u00e1rias vezes, ent\u00e3o ele tem experi\u00eancia em sentir o jogo de luta agarrada de algu\u00e9m no ch\u00e3o e utilizar seu controle por cima e press\u00e3o para anular a maioria das ofensivas.<br><br>N\u00f3s realmente n\u00e3o vemos como Solecki pode vencer isso, exceto em uma situa\u00e7\u00e3o milagrosa em que ele de alguma forma encontre as costas de Aliev e aplique um mata-le\u00e3o, ent\u00e3o acreditamos que Aliev tem essa luta garantida.<\/p>\n\n\n\n<div id=\"advad-gambyl-1856592013\" class=\"house advad-gambyl-third-paragraph advad-gambyl-entity-placement\" style=\"margin-top: 10px;margin-right: 10px;margin-bottom: 10px;margin-left: 10px;clear: both;\" data-cfpa=\"31717\" data-cfpw=\"31717\"><h2><strong><span style=\"color:#F0BE00;font-weight:800;\">Aten\u00e7\u00e3o novos jogadores!<\/span><\/strong><\/h2>\r\n\t<img src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA4MDAgMTk3IiB3aWR0aD0iODAwIiBoZWlnaHQ9IjE5NyIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDI0JTJGMDclMkZHYW1ieWxfZ29sZF9sb2dvcy13aGl0ZS1zcGFuaXNoLTEucG5nIiBkYXRhLXc9IjgwMCIgZGF0YS1oPSIxOTciIGRhdGEtYmlwPSIiPjwvc3ZnPg==\" data-spai=\"1\" alt=\"Gambyl\" width=\"125\" height=\"36\">\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Aposte em esportes legalmente na Bolsa de Apostas Gambyl. Oferta para novos jogadores: $10 USD para todas as novas contas verificadas, mais um b\u00f4nus de 100% no seu primeiro dep\u00f3sito.<\/a><\/p>\t\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Junte-se hoje!<\/a><\/p>\r\n<\/div><br style=\"clear: both; display: block; float: none;\"\/><script type=\"text\/javascript\">;new advadsCfpAd( 31717 );<\/script><h2 class=\"wp-block-heading\"><strong>MackeDern vs. Ribas<\/strong> Palpite de aposta: <strong>Amanda Ribas<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Ponzinibbio vs. Harris<\/strong> Palpite de aposta: <strong>Santiago Ponzinibbio<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Alhassan vs. Almeida<\/strong> Palpite de aposta: <strong>C\u00e9sar Almeida<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Curtis contra Kopylov<\/strong> Palpite de aposta: <strong>Roman Kopylov<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Bashi vs. Rodriguez<\/strong> Palpite de aposta: <strong>Christian Rodriguez<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Soriano vs. Medic<\/strong> Palpite de aposta: <strong>M\u00e9dico Uros<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Johnson contra Bunes<\/strong> Palpite de aposta: <strong>Jos\u00e9 Johnson<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Tulio vs. Poti\u00e9ria<\/strong> Palpite de aposta: <strong>Marco T\u00falio<\/strong><\/h2>\n\n\n\n<div id=\"advad-gambyl-3829033398\" class=\"house advad-gambyl-third-paragraph advad-gambyl-entity-placement\" style=\"margin-top: 10px;margin-right: 10px;margin-bottom: 10px;margin-left: 10px;clear: both;\" data-cfpa=\"31717\" data-cfpw=\"31717\"><h2><strong><span style=\"color:#F0BE00;font-weight:800;\">Aten\u00e7\u00e3o novos jogadores!<\/span><\/strong><\/h2>\r\n\t<img src=\"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA4MDAgMTk3IiB3aWR0aD0iODAwIiBoZWlnaHQ9IjE5NyIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDI0JTJGMDclMkZHYW1ieWxfZ29sZF9sb2dvcy13aGl0ZS1zcGFuaXNoLTEucG5nIiBkYXRhLXc9IjgwMCIgZGF0YS1oPSIxOTciIGRhdGEtYmlwPSIiPjwvc3ZnPg==\" data-spai=\"1\" alt=\"Gambyl\" width=\"125\" height=\"36\">\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Aposte em esportes legalmente na Bolsa de Apostas Gambyl. Oferta para novos jogadores: $10 USD para todas as novas contas verificadas, mais um b\u00f4nus de 100% no seu primeiro dep\u00f3sito.<\/a><\/p>\t\r\n<p><a style=\"color:white;\" href=\"http:\/\/exchange.gambyl.com\/signinredirection\" data-bid=\"1\" data-no-instant=\"1\" rel=\"noopener\">Junte-se hoje!<\/a><\/p>\r\n<\/div><br style=\"clear: both; display: block; float: none;\"\/><script type=\"text\/javascript\">;new advadsCfpAd( 31717 );<\/script><h2 class=\"wp-block-heading\"><strong>Mois\u00e9s vs. Ogden<\/strong> Palpite de aposta: <strong>Thiago Mois\u00e9s<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Parsons contra Smith<\/strong> Palpite de aposta: <strong>Jacob Smith (Portugu\u00eas)<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Kareckaite vs. Caliari<\/strong> Palpite de aposta: <strong>Ernesta Kareckaite<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Gadzhiyasulov vs. Lopes<\/strong> Palpite de aposta: <strong>Magomed Gadzhiyasulov<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Dudakova vs. Kline<\/strong> Palpite de aposta: <strong>F\u00e1tima Kline<\/strong><\/h2>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Solecki vs. Aliev <\/strong>Palpite de aposta: <strong>Nurullo Aliev<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-ink-adddata-ink-adddata-ink\"><\/div>","protected":false},"excerpt":{"rendered":"<p>The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December to give this event it&#8217;s main fight as two strawweights go back at each other to see who is likely to be on the track [&hellip;]<\/p>","protected":false},"author":1,"featured_media":32507,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_lmt_disableupdate":"","_lmt_disable":"","footnotes":"","_wpscp_schedule_draft_date":"","_wpscp_schedule_republish_date":"","_wpscppro_advance_schedule":false,"_wpscppro_advance_schedule_date":"","_wpscppro_dont_share_socialmedia":false,"_wpscppro_custom_social_share_image":0,"_facebook_share_type":"","_twitter_share_type":"","_linkedin_share_type":"","_pinterest_share_type":"","_linkedin_share_type_page":"","_instagram_share_type":"","_medium_share_type":"","_threads_share_type":"","_google_business_share_type":"","_selected_social_profile":[],"_wpsp_enable_custom_social_template":false,"_wpsp_social_scheduling":{"enabled":false,"datetime":null,"platforms":[],"status":"template_only","dateOption":"today","timeOption":"now","customDays":"","customHours":"","customDate":"","customTime":"","schedulingType":"absolute"},"_wpsp_active_default_template":true},"categories":[91],"tags":[406,134],"class_list":["post-40407","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ufc","tag-ufc-fight-night","tag-ufc-mma-octagon"],"aioseo_notices":[],"modified_by":"Erwin Noguera","aioseo_head":"\n\t\t<!-- All in One SEO Pro 4.9.7 - aioseo.com -->\n\t<meta name=\"description\" content=\"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gambyl Nation Editorial Team\"\/>\n\t<meta name=\"google-site-verification\" content=\"g4nMgEUwH_EUeAHO1on7tJ8dc_UVEdTvD7NXvjDBtYI\" \/>\n\t<meta name=\"msvalidate.01\" content=\"11AACE468E54A2AFF018B9903D7E59EC\" \/>\n\t<meta name=\"p:domain_verify\" content=\"2dd0267387e90e116bf3240265818d71\" \/>\n\t<meta name=\"yandex-verification\" content=\"07d0c340775b3ea0\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO Pro (AIOSEO) 4.9.7\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_PT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Gambyl Sports Betting Exchange - Bet on Sports Where The House Never Wins\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks - Gambyl Sports Betting Exchange\" \/>\n\t\t<meta property=\"og:description\" content=\"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.gambyl.com\/wp-content\/uploads\/2024\/07\/UFC-Fight-Night.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.gambyl.com\/wp-content\/uploads\/2024\/07\/UFC-Fight-Night.png\" \/>\n\t\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-01-09T21:49:36+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2025-01-09T21:49:39+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/realgambyl\/\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@realgambyl\" \/>\n\t\t<meta name=\"twitter:title\" content=\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\" \/>\n\t\t<meta name=\"twitter:description\" content=\"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@realgambyl\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.gambyl.com\/wp-content\/uploads\/2024\/07\/UFC-Fight-Night.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#blogposting\",\"name\":\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\",\"headline\":\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\",\"author\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/UFC-Fight-Night.png\",\"width\":1200,\"height\":800},\"datePublished\":\"2025-01-09T15:49:36-06:00\",\"dateModified\":\"2025-01-09T15:49:39-06:00\",\"inLanguage\":\"pt-PT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#webpage\"},\"articleSection\":\"UFC, UFC Fight Night, UFC. MMA. Octagon\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/#listItem\",\"name\":\"UFC\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/#listItem\",\"position\":2,\"name\":\"UFC\",\"item\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#listItem\",\"name\":\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#listItem\",\"position\":3,\"name\":\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/#listItem\",\"name\":\"UFC\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\",\"name\":\"Gambyl Sports Betting Exchange\",\"description\":\"Bet on Sports Where The House Never Wins\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"email\":\"hola@gambyl.com\",\"telephone\":\"+19012059469\",\"foundingDate\":\"2022-06-01\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-gambyl_logo.jpg\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#organizationLogo\",\"width\":512,\"height\":512,\"caption\":\"Gambyl Thumbnail Logo Purple\"},\"image\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/realgambyl\\\/\",\"https:\\\/\\\/twitter.com\\\/realgambyl\\\/\",\"https:\\\/\\\/instagram.com\\\/realgambyl_es\\\/\",\"https:\\\/\\\/tiktok.com\\\/@realgambyl\",\"https:\\\/\\\/www.pinterest.ca\\\/realgambyl\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7DMuQpsBQaIsDhTcGQt-Ow\",\"https:\\\/\\\/reddit.com\\\/r\\\/gambyl\",\"https:\\\/\\\/discord.gg\\\/dZewkvMNgx\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/\",\"name\":\"Gambyl Nation Editorial Team\",\"description\":\"Gambyl sports betting staff writers based are based in Mexico, South America and Canada. Our editorial writing team have combined experience of over 50 years in the sports betting and handicapping industries as both players and industry pros.\",\"jobTitle\":\"Staff Writer\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-gambyl_logo.jpg\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#webpage\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/\",\"name\":\"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\",\"description\":\"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December\",\"inLanguage\":\"pt-PT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/gambyl\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/UFC-Fight-Night.png\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#mainImage\",\"width\":1200,\"height\":800},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/ufc\\\/noite-de-luta-ufc-dern-vs-ribas-2\\\/#mainImage\"},\"datePublished\":\"2025-01-09T15:49:36-06:00\",\"dateModified\":\"2025-01-09T15:49:39-06:00\",\"reviewedBy\":{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/erwin\\\/#author\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/author\\\/erwin\\\/\",\"name\":\"Erwin Noguera\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/cdn.shortpixel.ai\\\/spai\\\/q_lossless+ret_img+to_webp\\\/www.gambyl.com\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/cropped-gambyl_logo.jpg\"}}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/\",\"name\":\"Gambyl Sports Betting Exchange\",\"alternateName\":\"Gambyl Sports\",\"description\":\"Bet on Sports Where The House Never Wins\",\"inLanguage\":\"pt-PT\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.gambyl.com\\\/pt\\\/#organization\"}}]}<\/script>\n\t\t<script type=\"text\/javascript\">\n\t\t\t(function(c,l,a,r,i,t,y){\n\t\t\tc[a]=c[a]||function(){(c[a].q=c[a].q||[]).push(arguments)};t=l.createElement(r);t.async=1;\n\t\t\tt.src=\"https:\/\/www.clarity.ms\/tag\/\"+i+\"?ref=aioseo\";y=l.getElementsByTagName(r)[0];y.parentNode.insertBefore(t,y);\n\t\t})(window, document, \"clarity\", \"script\", \"hxcfb9ve51\");\n\t\t<\/script>\n\t\t<!-- All in One SEO Pro -->\r\n\t\t<title>UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks<\/title>\n\n","aioseo_head_json":{"title":"UFC Fight Night: Dern vs Ribas 2 Probabilidades e escolhas do card de luta","description":"O UFC est\u00e1 levando esta pr\u00f3xima noite de luta para o UFC Apex em Las Vegas, Nevada, e teremos uma revanche que foi remarcada de meados de dezembro","canonical_url":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"g4nMgEUwH_EUeAHO1on7tJ8dc_UVEdTvD7NXvjDBtYI","msvalidate.01":"11AACE468E54A2AFF018B9903D7E59EC","p:domain_verify":"2dd0267387e90e116bf3240265818d71","yandex-verification":"07d0c340775b3ea0","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#blogposting","name":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","headline":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","author":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"publisher":{"@id":"https:\/\/www.gambyl.com\/pt\/#organization"},"image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","width":1200,"height":800},"datePublished":"2025-01-09T15:49:36-06:00","dateModified":"2025-01-09T15:49:39-06:00","inLanguage":"pt-PT","mainEntityOfPage":{"@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#webpage"},"isPartOf":{"@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#webpage"},"articleSection":"UFC, UFC Fight Night, UFC. MMA. Octagon"},{"@type":"BreadcrumbList","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/#listItem","position":1,"name":"Home","item":"https:\/\/www.gambyl.com\/pt\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/#listItem","name":"UFC"}},{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/#listItem","position":2,"name":"UFC","item":"https:\/\/www.gambyl.com\/pt\/ufc\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#listItem","name":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#listItem","position":3,"name":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","previousItem":{"@type":"ListItem","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/#listItem","name":"UFC"}}]},{"@type":"Organization","@id":"https:\/\/www.gambyl.com\/pt\/#organization","name":"Gambyl Sports Betting Exchange","description":"Bet on Sports Where The House Never Wins","url":"https:\/\/www.gambyl.com\/pt\/","email":"hola@gambyl.com","telephone":"+19012059469","foundingDate":"2022-06-01","logo":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA1MTIgNTEyIiB3aWR0aD0iNTEyIiBoZWlnaHQ9IjUxMiIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDElMkZjcm9wcGVkLWdhbWJ5bF9sb2dvLmpwZyIgZGF0YS13PSI1MTIiIGRhdGEtaD0iNTEyIiBkYXRhLWJpcD0iIj48L3N2Zz4=","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#organizationLogo","width":512,"height":512,"caption":"Gambyl Thumbnail Logo Purple"},"image":{"@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#organizationLogo"},"sameAs":["https:\/\/facebook.com\/realgambyl\/","https:\/\/twitter.com\/realgambyl\/","https:\/\/instagram.com\/realgambyl_es\/","https:\/\/tiktok.com\/@realgambyl","https:\/\/www.pinterest.ca\/realgambyl\/","https:\/\/www.youtube.com\/channel\/UC7DMuQpsBQaIsDhTcGQt-Ow","https:\/\/reddit.com\/r\/gambyl","https:\/\/discord.gg\/dZewkvMNgx"]},{"@type":"Person","@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author","url":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/","name":"Gambyl Nation Editorial Team","description":"Gambyl sports betting staff writers based are based in Mexico, South America and Canada. Our editorial writing team have combined experience of over 50 years in the sports betting and handicapping industries as both players and industry pros.","jobTitle":"Staff Writer","image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA1MTIgNTEyIiB3aWR0aD0iNTEyIiBoZWlnaHQ9IjUxMiIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDElMkZjcm9wcGVkLWdhbWJ5bF9sb2dvLmpwZyIgZGF0YS13PSI1MTIiIGRhdGEtaD0iNTEyIiBkYXRhLWJpcD0iIj48L3N2Zz4="}},{"@type":"WebPage","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#webpage","url":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/","name":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","description":"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December","inLanguage":"pt-PT","isPartOf":{"@id":"https:\/\/www.gambyl.com\/pt\/#website"},"breadcrumb":{"@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#breadcrumblist"},"author":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"creator":{"@id":"https:\/\/www.gambyl.com\/pt\/author\/gambyl\/#author"},"image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#mainImage","width":1200,"height":800},"primaryImageOfPage":{"@id":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/#mainImage"},"datePublished":"2025-01-09T15:49:36-06:00","dateModified":"2025-01-09T15:49:39-06:00","reviewedBy":{"@type":"Person","@id":"https:\/\/www.gambyl.com\/pt\/author\/erwin\/#author","url":"https:\/\/www.gambyl.com\/pt\/author\/erwin\/","name":"Erwin Noguera","image":{"@type":"ImageObject","url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCA1MTIgNTEyIiB3aWR0aD0iNTEyIiBoZWlnaHQ9IjUxMiIgZGF0YS11PSJodHRwcyUzQSUyRiUyRnd3dy5nYW1ieWwuY29tJTJGd3AtY29udGVudCUyRnVwbG9hZHMlMkYyMDIxJTJGMDElMkZjcm9wcGVkLWdhbWJ5bF9sb2dvLmpwZyIgZGF0YS13PSI1MTIiIGRhdGEtaD0iNTEyIiBkYXRhLWJpcD0iIj48L3N2Zz4="}}},{"@type":"WebSite","@id":"https:\/\/www.gambyl.com\/pt\/#website","url":"https:\/\/www.gambyl.com\/pt\/","name":"Gambyl Sports Betting Exchange","alternateName":"Gambyl Sports","description":"Bet on Sports Where The House Never Wins","inLanguage":"pt-PT","publisher":{"@id":"https:\/\/www.gambyl.com\/pt\/#organization"}}]},"og:locale":"pt_PT","og:site_name":"Gambyl Sports Betting Exchange - Bet on Sports Where The House Never Wins","og:type":"article","og:title":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks - Gambyl Sports Betting Exchange","og:description":"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.","og:url":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/","og:image":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","og:image:secure_url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","og:image:width":"1200","og:image:height":"800","article:published_time":"2025-01-09T21:49:36+00:00","article:modified_time":"2025-01-09T21:49:39+00:00","article:publisher":"https:\/\/facebook.com\/realgambyl\/","twitter:card":"summary_large_image","twitter:site":"@realgambyl","twitter:title":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","twitter:description":"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.","twitter:creator":"@realgambyl","twitter:image":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg=="},"aioseo_meta_data":{"post_id":"40407","title":"#post_title","description":"O UFC est\u00e1 levando esta pr\u00f3xima noite de luta para o UFC Apex em Las Vegas, Nevada, e teremos uma revanche que foi remarcada de meados de dezembro","keywords":null,"keyphrases":{"focus":{"keyphrase":"UFC","score":85,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":1},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}},"additional":[{"keyphrase":"fight night","score":75,"analysis":{"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":2},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInImageAlt":[],"keywordDensity":{"score":0,"type":"low","maxScore":9,"error":1}}}]},"primary_term":null,"canonical_url":null,"og_title":"#post_title #separator_sa #site_title","og_description":"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.","og_object_type":"default","og_image_type":"featured","og_image_url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","og_image_width":"1200","og_image_height":"800","og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"featured","twitter_image_url":"data:image\/svg+xml;base64,PHN2ZyB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciIHZpZXdCb3g9IjAgMCAxMjAwIDgwMCIgd2lkdGg9IjEyMDAiIGhlaWdodD0iODAwIiBkYXRhLXU9Imh0dHBzJTNBJTJGJTJGd3d3LmdhbWJ5bC5jb20lMkZ3cC1jb250ZW50JTJGdXBsb2FkcyUyRjIwMjQlMkYwNyUyRlVGQy1GaWdodC1OaWdodC5wbmciIGRhdGEtdz0iMTIwMCIgZGF0YS1oPSI4MDAiIGRhdGEtYmlwPSIiPjwvc3ZnPg==","twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":"#post_title","twitter_description":"The UFC is taking this upcoming fight night to the UFC Apex in Las Vegas, Nevada, and we are getting a rematch that was rescheduled from the middle of December.","schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"seo_analyzer_scan_date":null,"breadcrumb_settings":null,"limit_modified_date":0,"reviewed_by":"16","open_ai":"{\"title\":{\"suggestions\":[],\"usage\":0},\"description\":{\"suggestions\":[],\"usage\":0}}","ai":null,"created":"2025-01-09 21:43:21","updated":"2025-01-09 21:49:40"},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.gambyl.com\/pt\/\" title=\"Home\">Home<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\t<a href=\"https:\/\/www.gambyl.com\/pt\/ufc\/\" title=\"UFC\">UFC<\/a>\n<\/span><span class=\"aioseo-breadcrumb-separator\">\/<\/span><span class=\"aioseo-breadcrumb\">\n\tUFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks\n<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.gambyl.com\/pt\/"},{"label":"UFC","link":"https:\/\/www.gambyl.com\/pt\/ufc\/"},{"label":"UFC Fight Night: Dern vs Ribas 2 Fight Card Odds and Picks","link":"https:\/\/www.gambyl.com\/pt\/ufc\/noite-de-luta-ufc-dern-vs-ribas-2\/"}],"authors":[],"_links":{"self":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts\/40407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/comments?post=40407"}],"version-history":[{"count":0,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/posts\/40407\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/media\/32507"}],"wp:attachment":[{"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/media?parent=40407"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/categories?post=40407"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.gambyl.com\/pt\/wp-json\/wp\/v2\/tags?post=40407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}